{"id":32298,"date":"2024-11-06T14:00:00","date_gmt":"2024-11-06T05:00:00","guid":{"rendered":"https:\/\/designcompass.org\/?p=32298"},"modified":"2024-11-05T21:48:13","modified_gmt":"2024-11-05T12:48:13","slug":"nintendo-music","status":"publish","type":"post","link":"https:\/\/designcompass.org\/en\/2024\/11\/06\/nintendo-music\/","title":{"rendered":"Nintendo Music: A music app that bursts with emotion"},"content":{"rendered":"<p>Nintendo has released a music service called &#039;Nintendo Music&#039;. You can listen to famous game music such as Mario, The Legend of Zelda, Animal Crossing, and Splatoon. In addition, you can listen to background music from games released by Nintendo over a period of over 40 years.<\/p>\n\n\n\n<p>You can stream songs or download them to the app to listen offline. Search for songs by song title, track name, playlist, or find them by screenshot. Repeat songs like a regular music app. Filter out songs that contain spoilers. Create your own playlists of your favorite songs or listen to Nintendo-created playlists. It even recommends music that matches characters or game moments based on what you did on your Nintendo Switch.<\/p>\n\n\n\n<p>It supports iOS and Android and is available only to Nintendo Switch Online members. If it&#039;s your first time, you can try it for free for 7 days.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-14-1024x576.png\" alt=\"\" class=\"wp-image-32306\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-14-1024x576.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-14-300x169.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-14-768x432.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-14-1536x864.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-14-18x10.png 18w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-14-1320x743.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-14-600x338.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-14.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u24d2Nintendo<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-04-1024x576.png\" alt=\"\" class=\"wp-image-32301\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-04-1024x576.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-04-300x169.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-04-768x432.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-04-1536x864.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-04-18x10.png 18w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-04-1320x743.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-04-600x338.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-04.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u24d2Nintendo<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-06-1024x576.png\" alt=\"\" class=\"wp-image-32302\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-06-1024x576.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-06-300x169.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-06-768x432.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-06-1536x864.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-06-18x10.png 18w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-06-1320x743.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-06-600x338.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-06.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u24d2Nintendo<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-08-1024x576.png\" alt=\"\" class=\"wp-image-32303\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-08-1024x576.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-08-300x169.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-08-768x432.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-08-1536x864.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-08-18x10.png 18w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-08-1320x743.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-08-600x338.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-08.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u24d2Nintendo<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-10-1024x576.png\" alt=\"\" class=\"wp-image-32304\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-10-1024x576.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-10-300x169.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-10-768x432.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-10-1536x864.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-10-18x10.png 18w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-10-1320x743.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-10-600x338.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-10.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u24d2Nintendo<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-12-1024x576.png\" alt=\"\" class=\"wp-image-32305\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-12-1024x576.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-12-300x169.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-12-768x432.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-12-1536x864.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-12-18x10.png 18w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-12-1320x743.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-12-600x338.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-12.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u24d2Nintendo<\/figcaption><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">More and Sources<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.nintendo.co.kr\/news\/article\/6s7H9EHLm2pkvQdq9nEkFP\">https:\/\/www.nintendo.co.kr\/news\/article\/6s7H9EHLm2pkvQdq9nEkFP<\/a><\/li>\n<\/ul>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>","protected":false},"excerpt":{"rendered":"<p>\ub2cc\ud150\ub3c4\uac00 \uc74c\uc545 \uc11c\ube44\uc2a4 \u2018\ub2cc\ud150\ub3c4 \ubba4\uc9c1\u2019\uc744 \ubc30\ud3ec\ud588\uc2b5\ub2c8\ub2e4. \ub9c8\ub9ac\uc624, \uc824\ub2e4\uc758 \uc804\uc124, \ub3d9\ubb3c\uc758 \uc232, \uc2a4\ud50c\ub798\ud230 \ub4f1 \uc720\uba85 \uac8c\uc784 \uc74c\uc545\uc744 \ub4e4\uc744 \uc218 \uc788\uc2b5\ub2c8\ub2e4. \uadf8\ubfd0\ub9cc \uc544\ub2c8\ub77c \ubb34\ub824 40\ub144\uc774 \ub118\ub294 \uc138\uc6d4 \ub3d9\uc548 \ub2cc\ud150\ub3c4\uac00 \ubc1c\ub9e4\ud55c \uac8c\uc784\uc758 \ubc30\uacbd \uc74c\uc545\uc744 \ub4e4\uc744 \uc218 \uc788\uc2b5\ub2c8\ub2e4. \ub178\ub798\ub97c \uc2a4\ud2b8\ub9ac\ubc0d\ud558\uac70\ub098 \uc571\uc5d0 \ub2e4\uc6b4\ub85c\ub4dc\ud574 \uc624\ud504\ub77c\uc778\uc5d0\uc11c \ub4e4\uc744 \uc218 \uc788\uc2b5\ub2c8\ub2e4. \ub178\ub798 \uc81c\ubaa9, \ud2b8\ub799 \uc774\ub984, \uc7ac\uc0dd \ubaa9\ub85d\uc73c\ub85c \ub178\ub798\ub97c \uac80\uc0c9\ud558\uac70\ub098 \uc2a4\ud06c\ub9b0\uc0f7\uc73c\ub85c \ucc3e\uc744 \uc218 \uc788\uc2b5\ub2c8\ub2e4. \uc77c\ubc18\uc801\uc778 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":32300,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4,621],"tags":[459,573,1470],"class_list":["post-32298","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-service","tag-459","tag-573","tag-1470"],"acf":[],"jetpack_featured_media_url":"https:\/\/designcompass.org\/wp-content\/uploads\/2024\/11\/nintendomusic-01.png","publishpress_future_action":{"enabled":false,"date":"2026-05-21 05:58:53","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/posts\/32298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/comments?post=32298"}],"version-history":[{"count":0,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/posts\/32298\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/media\/32300"}],"wp:attachment":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/media?parent=32298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/categories?post=32298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/tags?post=32298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}