{"id":20672,"date":"2023-11-23T18:00:00","date_gmt":"2023-11-23T09:00:00","guid":{"rendered":"https:\/\/designcompass.org\/?p=20672"},"modified":"2025-06-06T13:34:21","modified_gmt":"2025-06-06T04:34:21","slug":"ux-class-update-lv2-4","status":"publish","type":"post","link":"https:\/\/designcompass.org\/en\/2023\/11\/23\/ux-design-class-lv3-update\/","title":{"rendered":"UX Design Class Update: Investigating LV3 Experiences Completed"},"content":{"rendered":"<p>We are working hard to create a UX design class. Completed the chapter \u2018Examining the LV3 Experience\u2019.<\/p>\n\n\n\n<p>The world is more complicated than you think. Since I have no choice but to make complex things simple to make it easier for me to think about them, problems are bound to arise at each step. There are many times when what I thought I knew was actually different. However, we cannot leave everything unknown. So what should you do?<\/p>\n\n\n\n<p>This is asking the user.<\/p>\n\n\n\n<p>What you need to do before asking is to define what you need to find out. Using the example above, you might be asking, \u201cWhy would I change jobs?\u201d I need to gather as much information as I can right now and figure out what I don&#039;t know. Consider all the possible cases, come up with a hypothesis, and reduce and reduce the number until you can&#039;t reduce it any further. Define what you would like to test if you could fire just one arrow.<\/p>\n\n\n\n<p>There is only one LV4 left until the next UX class opens. Receive opening notifications now and learn the essence of UX design to make an impact in startups faster than anyone else!<\/p>\n\n\n\n<div class=\"wp-block-buttons has-custom-font-size has-medium-font-size is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/designcompass.org\/en\/courses\/ux-design-preview\/\">Go to lecture<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-02-1-1024x1024.png\" alt=\"\" class=\"wp-image-20676\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-02-1-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-02-1-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-02-1-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-02-1-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-02-1-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-02-1-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-02-1-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-02-1-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-02-1-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-02-1-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-02-1-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-02-1.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-03-1-1024x1024.png\" alt=\"\" class=\"wp-image-20677\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-03-1-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-03-1-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-03-1-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-03-1-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-03-1-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-03-1-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-03-1-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-03-1-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-03-1-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-03-1-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-03-1-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-03-1.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-04-1-1024x1024.png\" alt=\"\" class=\"wp-image-20678\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-04-1-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-04-1-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-04-1-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-04-1-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-04-1-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-04-1-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-04-1-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-04-1-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-04-1-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-04-1-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-04-1-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-04-1.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-05-1-1024x1024.png\" alt=\"\" class=\"wp-image-20679\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-05-1-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-05-1-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-05-1-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-05-1-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-05-1-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-05-1-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-05-1-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-05-1-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-05-1-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-05-1-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-05-1-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-05-1.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>\uc5f4\uc2ec\ud788 UX \ub514\uc790\uc778 \ud074\ub798\uc2a4\ub97c \ub9cc\ub4e4\uace0 \uc788\uc2b5\ub2c8\ub2e4. \u2018LV3 \uacbd\ud5d8\uc744 \uc870\uc0ac\ud558\uae30\u2019 \ucc55\ud130\ub97c \uc644\uc131\ud588\uc2b5\ub2c8\ub2e4. \uc138\uc0c1\uc740 \uc0dd\uac01\ubcf4\ub2e4 \ubcf5\uc7a1\ud569\ub2c8\ub2e4. \ub0b4\uac00 \uc0dd\uac01\ud558\uae30 \ud3b8\ud558\uac8c \ubcf5\uc7a1\ud55c \uac83\uc744 \ub2e8\uc21c\ud558\uac8c \ub9cc\ub4e4 \uc218 \ubc16\uc5d0 \uc5c6\uae30 \ub54c\ubb38\uc5d0 \uac01 \ub2e8\uacc4\ubcc4\ub85c \ubb38\uc81c\uac00 \uc0dd\uae38 \uc218\ubc16\uc5d0 \uc5c6\uc2b5\ub2c8\ub2e4. \ub0b4\uac00 \uc54c\uace0 \uc788\ub2e4 \uc0dd\uac01\ud55c \uac83\ub3c4 \uc0ac\uc2e4 \ub2e4\ub97c \ub54c\uac00 \ub9ce\uc8e0. \uadf8\ub807\ub2e4\uace0 \ubaa8\ub4e0 \uac83\uc744 \ubbf8\uc9c0\uc218\ub85c \ub0a8\uaca8\ub458 \uc218\ub3c4 \uc5c6\uc2b5\ub2c8\ub2e4. \uadf8\ub807\ub2e4\uba74 \ubb34\uc5c7\uc744 \ud574\uc57c \ud560\uae4c\uc694? \uc0ac\uc6a9\uc790\uc5d0\uac8c \ubb3c\uc5b4\ubcf4\ub294 \uac83\uc785\ub2c8\ub2e4. \ubb3b\uae30 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20675,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[891],"tags":[],"class_list":["post-20672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-891"],"acf":[],"jetpack_featured_media_url":"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/update-ux-class-lv2-1.png","publishpress_future_action":{"enabled":false,"date":"2026-05-21 06:21:39","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/posts\/20672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/comments?post=20672"}],"version-history":[{"count":0,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/posts\/20672\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/media\/20675"}],"wp:attachment":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/media?parent=20672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/categories?post=20672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/tags?post=20672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}