{"id":19502,"date":"2023-11-09T10:28:09","date_gmt":"2023-11-09T01:28:09","guid":{"rendered":"https:\/\/designcompass.org\/?p=19502"},"modified":"2023-11-09T10:30:29","modified_gmt":"2023-11-09T01:30:29","slug":"airbnb-2023-winter-update","status":"publish","type":"post","link":"https:\/\/designcompass.org\/en\/2023\/11\/09\/airbnb-2023-winter-update\/","title":{"rendered":"Aver&amp;B 2023 Winter Large-scale Update: What\u2019s Changed?"},"content":{"rendered":"\n<p>\uc5d0\uc5b4\ube44\uc564\ube44\uac00 \uaca8\uc6b8\uc744 \ub9de\uc544 \uc0c8\ub85c\uc6b4 \uae30\ub2a5\uc744 \uc120\ubcf4\uc785\ub2c8\ub2e4. \uac1c\uc131 \ub118\uce58\ub294 \ub3c5\ud2b9\ud55c \uc219\uc18c\ub97c \uc18c\uac1c\ud558\ub294 \uc5d0\uc5b4\ube44\uc564\ube44\uc5d0\uc11c \ubb34\uc5c7\uc744 \uc120\ud0dd\ud574\uc57c\ud560\uc9c0 \uc5b4\ub824\uc6cc\ud558\ub294 \uc0ac\ub78c\ub4e4\uc744 \uc704\ud55c \uc0c8\ub85c\uc6b4 \uae30\ub2a5\uc744 \uc81c\uacf5\ud569\ub2c8\ub2e4.<\/p>\n\n\n\n<p>\uc0ac\uc6a9\uc790\uac00 \uac8c\uc2a4\ud2b8\uc640 \uc219\uc18c\uc5d0 \uad00\ud574 \ub354 \ubbff\uc744\ub9cc\ud55c \uc815\ubcf4\ub97c \uc5bb\uc744 \uc218 \uc788\uace0 \ud638\uc2a4\ud2b8\ub294 \uc27d\uace0 \ud3b8\ud558\uac8c \uc815\ubcf4\ub97c \ub4f1\ub85d\ud558\uace0 \uad00\ub9ac\ud560 \uc218 \uc788\uac8c \ubc14\ub01d\ub2c8\ub2e4. \uc5c4\uaca9\ud55c \uae30\uc900\uc73c\ub85c \uc120\uc815\ud55c \uc219\uc18c\uc778 \u2018Guest favorite\u2019, \uc219\uc18c \ud488\uc9c8\uc744 \ub354 \uc790\uc138\ud788 \ud655\uc778\ud560 \uc218 \uc788\ub294 \uac1c\uc120\ub41c \ud6c4\uae30, \ud638\uc2a4\ud2b8\ub97c \uc704\ud55c \uc0c8\ub85c\uc6b4 \uc219\uc18c \ud0ed \ud06c\uac8c 3\uac00\uc9c0 \uae30\ub2a5\uc744 \ubc1c\ud45c\ud588\uc2b5\ub2c8\ub2e4.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83d\udc41\ufe0f&nbsp;\ub514\uc790\uc774\ub108\uc758 \ub208<\/h3>\n\n\n\n<p><strong>Guest favorite<\/strong><\/p>\n\n\n\n<p>\ub9ce\uc740 \uac8c\uc2a4\ud2b8\uc758 \uc120\ud0dd\uc744 \ubc1b\uc740 \uc219\uc18c\ub97c \ubcc4\ub3c4 \ubc43\uc9c0\ub85c \ud45c\uc2dc\ud569\ub2c8\ub2e4. \ubaa9\ub85d\uc5d0\uc11c\ub294 \uce74\ub4dc\uc758 \uc67c\ucabd \uc0c1\ub2e8\uc5d0 Guest favorite \ubc43\uc9c0\uac00 \ub208\uc5d0 \ub744\uac8c \ubc30\uce58\ub429\ub2c8\ub2e4. \uc219\uc18c \uc0c1\uc138\uc5d0\uc11c\ub294 \ubcc4\ub3c4\uc758 \uc120\uc73c\ub85c \ud6c4\uae30 \uc815\ubcf4\ub97c \ubb36\uace0 \ubc43\uc9c0\ub97c \uac00\uc6b4\ub370\uc5d0 \ubc30\uce58\ud574 \uc2dc\uc120\uc774 \uc790\uc5f0\uc2a4\ub7fd\uac8c \uc9d1\uc911\ud558\uac8c \ub9cc\ub4ed\ub2c8\ub2e4. \ubaa8\uc74d\ub2c8\ub2e4. Guest favorite \uc591 \uc606\uc5d0 \uc6d4\uacc4\uad00\uc744 \ubc30\uce58\ud574 \ub354 \uac15\ud558\uac8c \uac15\uc870\ud569\ub2c8\ub2e4. \uae30\uc874 \uc544\ud2b8\uc6cc\ud06c\uc758 \uc2dc\uac01 \uaddc\uce59\uc5d0 \ub9de\uac8c \uad75\uace0 \uc9c4\ud55c \uac80\uc740 \uc120\uc73c\ub85c \ud45c\ud604\ud588\uc2b5\ub2c8\ub2e4.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-04-1024x1024.png\" alt=\"\" class=\"wp-image-19513\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-04-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-04-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-04-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-04-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-04-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-04-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-04-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-04-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-04-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-04-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-04-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-04.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u00a9Airbnb<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-03-1024x1024.png\" alt=\"\" class=\"wp-image-19508\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-03-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-03-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-03-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-03-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-03-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-03-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-03-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-03-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-03-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-03-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-03-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-03.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u00a9Airbnb<\/figcaption><\/figure>\n\n\n\n<p>\uc219\uc18c \uc804\uccb4 \ud3c9\uc810\uc744 4.8 \uc774\uc0c1\uc73c\ub85c \uc720\uc9c0\ud574\uc57c \uc5bb\uc744 \uc218 \uc788\ub294 \u2018\uc288\ud37c \ud638\uc2a4\ud2b8\u2019\uacfc \ub9e5\ub77d\uc740 \ube44\uc2b7\ud558\uc9c0\ub9cc \u2018Guest favorite\u2019\uc740 \uc219\uc18c \uc790\uccb4\uc5d0 \ub354 \uc9d1\uc911\ub429\ub2c8\ub2e4. \uc288\ud37c \ud638\uc2a4\ud2b8\ub294 \ubd84\uae30\ubcc4\ub85c \uc5c5\ub370\uc774\ud2b8\ub418\uc9c0\ub9cc \u2018Guest favorite\u2019\uc740 \ub9e4\uc8fc \uc5c5\ub370\uc774\ud2b8\ub429\ub2c8\ub2e4.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>\uac1c\uc120\ub41c \ud6c4\uae30<\/strong><\/p>\n\n\n\n<p>\uc774\uc81c \ud6c4\uae30\ub97c \uc2dc\uac04\uc21c, \ud3c9\uc810\uc21c\uc73c\ub85c \uc815\ub82c\ud560 \uc218 \uc788\uc2b5\ub2c8\ub2e4. \ubcc4\uc810 \ud6c4\uae30\uc758 1\uc810\ubd80\ud130 5\uc810\uae4c\uc9c0 \ubd84\ud3ec\ub97c \ud655\uc778\ud560 \uc218 \uc788\uc2b5\ub2c8\ub2e4. \ud6c4\uae30\ub97c \uc791\uc131\ud55c \uc0ac\ub78c\uc758 \ub9e5\ub77d\ub3c4 \ucd94\uac00\ub429\ub2c8\ub2e4. \uc5b4\ub514 \ucd9c\uc2e0\uc774\uba70 \ub204\uad6c\uc640 \uc5bc\ub9c8\ub098 \uc624\ub798 \uc5ec\ud589\ud588\ub294\uc9c0\uac00 \ud45c\uc2dc\ub429\ub2c8\ub2e4.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-05-1024x1024.png\" alt=\"\" class=\"wp-image-19509\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-05-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-05-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-05-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-05-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-05-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-05-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-05-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-05-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-05-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-05-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-05-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-05.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u00a9Airbnb<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-06-1024x1024.png\" alt=\"\" class=\"wp-image-19510\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-06-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-06-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-06-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-06-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-06-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-06-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-06-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-06-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-06-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-06-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-06-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-06.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u00a9Airbnb<\/figcaption><\/figure>\n\n\n\n<p>\uad6c\uccb4\uc801\uc778 \uc22b\uc790\ubcf4\ub2e4\ub294 \uc804\uccb4\uc801\uc778 \ube44\uc728\uc744 \ud655\uc778\ud560 \uc218 \uc788\ub294 \ud615\ud0dc\uc785\ub2c8\ub2e4. \uc0c8\ub85c\uc6b4 \uc815\ubcf4\ub97c \uc904 \ub54c\ub9c8\ub2e4 \uc0c8\ub85c\uc6b4 \ud310\ub2e8\uc744 \ud574\uc57c\ud558\uae30 \ub54c\ubb38\uc5d0 \u2018\ubd84\ud3ec\u2019\ub97c \ube60\ub974\uac8c \ud310\ub2e8\ud560 \uc218 \uc788\uac8c \uc870\uadf8\ub9c8\ud558\uac8c \ud45c\ud604\ub418\uc5c8\uc2b5\ub2c8\ub2e4. \uc219\uc18c\uc5d0 \uad00\ud55c \ud56d\ubaa9\ubcc4 \ud3c9\uac00 \uc810\uc218\ub294 \uac00\ub85c\ub85c \uc2a4\ud06c\ub864\ud574 \ub354 \ud655\uc778\ud560 \uc218 \uc788\uc2b5\ub2c8\ub2e4. \uc5d0\uc5b4\ube44\uc564\ube44\ub2f5\uac8c \uc0c8\ub85c \ucd94\uac00\ub41c \ud56d\ubaa9\ub4e4\uc740 \uc0c9\uc774 \uc5c6\uc774 \ucd5c\uc18c\ud55c\uc758 \uadf8\ub798\ud53d\uc73c\ub85c \ud45c\ud604\ud588\uc2b5\ub2c8\ub2e4.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>\ud638\uc2a4\ud2b8\ub97c \uc704\ud55c \uae30\ub2a5<\/strong><\/p>\n\n\n\n<p>\ud638\uc2a4\ud2b8\uac00 \uc815\ubcf4\ub97c \uc798 \ub4f1\ub85d\ud558\uac8c \ub3d5\ub294 \ub2e4\uc591\ud55c \uae30\ub2a5\uc774 \uc5c5\ub370\uc774\ud2b8\ub418\uc5c8\uc2b5\ub2c8\ub2e4. \uc219\uc18c \ud398\uc774\uc9c0 \uc5d0\ub514\ud130\ub85c \ubaa8\ubc14\uc77c\ub85c \uc190\uc27d\uac8c \uc138\ubd80 \uc815\ubcf4\ub97c \ub4f1\ub85d\ud560 \uc218 \uc788\uc2b5\ub2c8\ub2e4. AI\uc758 \ub3c4\uc6c0\uc73c\ub85c \uc5ec\ub7ec \uc0ac\uc9c4\uc744 \uacf5\uac04\ubcc4\ub85c \ube60\ub974\uac8c \uc815\ub9ac\ud560 \uc218 \uc788\uac8c \ub418\uc5c8\uc2b5\ub2c8\ub2e4. \uc219\uc18c \uc608\uc57d\uc774 \uc644\ub8cc\ub418\uc5c8\uc744 \ub54c \uc54c\ub824\uc8fc\ub294 \uccb4\ud06c\uc778 \uac00\uc774\ub4dc\ub3c4 \ubbf8\ub9ac \ud655\uc778\ud560 \uc218 \uc788\uc2b5\ub2c8\ub2e4. \uc774\uc81c \ud638\uc2a4\ud305 \uc218\uc785\uc744 \ub354 \ud3b8\ub9ac\ud558\uac8c \uad00\ub9ac\ud560 \uc218 \uc788\ub294 \ub3c4\uad6c, \uacf5\ub3d9 \ud638\uc2a4\ud2b8, \uc694\uae08 \ube44\uad50, \uc219\uc18c \uc694\uae08\uc774 \ud45c\uc2dc\ub418\ub294 \ubc29\uc2dd\uc744 \uc81c\uc5b4\ud560 \uc218 \uc788\uc2b5\ub2c8\ub2e4.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-07-1024x1024.png\" alt=\"\" class=\"wp-image-19511\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-07-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-07-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-07-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-07-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-07-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-07-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-07-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-07-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-07-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-07-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-07-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-07.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u00a9Airbnb<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-08-1024x1024.png\" alt=\"\" class=\"wp-image-19512\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-08-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-08-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-08-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-08-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-08-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-08-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-08-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-08-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-08-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-08-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-08-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-08.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u00a9Airbnb<\/figcaption><\/figure>\n\n\n\n<p>\uc5d0\uc5b4\ube44\uc564\ube44\ub2f5\uac8c \uac04\uacb0\ud55c GUI\ub85c \uc0c8\ub85c\uc6b4 \uacbd\ud5d8\uc744 \uc81c\uacf5\ud569\ub2c8\ub2e4. \uc815\ub9d0 \uac15\uc870\ud558\uace0 \uc2f6\uc740 \uc601\uc5ed\uc5d0\ub9cc 2.5D \uc2a4\ud0c0\uc77c\uc758 \uc77c\ub7ec\uc2a4\ud2b8\ub808\uc774\uc158\uc73c\ub85c \uac15\uc870\ud558\ub294 \uac83\ub3c4 \uc88b\uc2b5\ub2c8\ub2e4. \ubaa8\ub450\uac00 \uc11c\ub85c \uc8fc\uc778\uacf5\uc774 \ub418\ub294 \uadf8\ub798\ud53d\ubcf4\ub2e4 \uc815\ub9d0 \uc911\uc694\ud55c \uac83\ub9cc \uac15\uc870\ud558\ub294 \uac83\uc774 \ub9e4\ub044\ub7fd\ub124\uc694.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>\uace0\ubbfc\uc744 \uc904\uc774\uace0 \uc219\uc18c\ub97c \uc120\ud0dd\ud558\uac8c \ub3d5\ub294 \uae30\ub2a5\uc5d0 \uc9d1\uc911\ud588\ub2e4\ub294 \uc0dd\uac01\uc774 \ub4ed\ub2c8\ub2e4. \uac8c\uc2a4\ud2b8\uac00 \uc544\ub2cc \uc219\uc18c\ub97c \uc5c4\uc120\ud558\ub294 Guest favorite\uacfc \ud310\ub2e8\uc5d0 \ud544\uc694\ud55c \uc815\ubcf4\ub97c \ucc3e\uac8c \ub9cc\ub4dc\ub294 \ud6c4\uae30\ub294 \ubaa9\uc801\uc740 \uac19\uc9c0\ub9cc \uc131\uaca9\uc774 \ub2e4\ub978 UX\uc778 \uac83 \uac19\uc2b5\ub2c8\ub2e4. \ubc43\uc9c0\ub294 \uc218\uc9d1\ud558\uace0 \ud310\ub2e8\ud560 \uc815\ubcf4\ub97c \ucd5c\uc18c\ud654\ud574 \ube60\ub974\uac8c \uace0\ub97c \uc218 \uc788\uac8c \ub3d5\ub294\ub2e4\uba74 \ud6c4\uae30 \uace0\ub3c4\ud654\ub294 \ud310\ub2e8\uc5d0 \ud544\uc694\ud55c \uc790\uc138\ud55c \uc815\ubcf4\ub97c \ucc3e\uc544 \uacb0\uc815\ud558\uac8c \ub3d5\ub294 \uacbd\ud5d8\uc774\ub124\uc694.<\/p>\n\n\n\n<p>\uc55e\uc73c\ub85c\ub294 \ub0b4\uac00 \ud50c\ub7ab\ud3fc\uc5d0\uc11c \ubcf4\uc774\ub294 \uc219\uc18c\uc640 \uc2e4\uc81c \uc219\uc18c\uc758 \ucc28\uc774\ub97c \uc904\uc774\ub294 \uae30\ub2a5\uc774 \ub9ce\uc544\uc9c0\uba74 \uc88b\uc744 \uac83 \uac19\uc2b5\ub2c8\ub2e4. \uc601\uc0c1\uc73c\ub85c \ub0b4\ubd80\ub97c \uacf5\uc720\ud560 \uc218\ub294 \uc5c6\uc744\uae4c \uc0dd\uac01\uc774 \ub4dc\ub124\uc694.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-10-1024x1024.png\" alt=\"\" class=\"wp-image-19514\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-10-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-10-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-10-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-10-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-10-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-10-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-10-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-10-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-10-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-10-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-10-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-10.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u00a9Airbnb<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-11-1024x1024.png\" alt=\"\" class=\"wp-image-19515\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-11-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-11-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-11-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-11-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-11-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-11-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-11-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-11-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-11-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-11-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-11-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-11.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u00a9Airbnb<\/figcaption><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">\ub354 \ubcf4\uae30 \ubc0f \ucd9c\ucc98<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.airbnb.co.kr\/release\">https:\/\/www.airbnb.co.kr\/release<\/a><\/li>\n<\/ul>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n  \n  \n  <div class=\"\n    mailpoet_form_popup_overlay\n      \"><\/div>\n  <div\n    id=\"mailpoet_form_1\"\n    class=\"\n      mailpoet_form\n      mailpoet_form_html\n      mailpoet_form_position_\n      mailpoet_form_animation_\n    \"\n      >\n\n    <style type=\"text\/css\">\n     #mailpoet_form_1 .mailpoet_form {  }\n#mailpoet_form_1 form { margin-bottom: 0; }\n#mailpoet_form_1 h1.mailpoet-heading { margin: 0px 0px 16px 0px; }\n#mailpoet_form_1 .mailpoet_form .mailpoet-has-font-size { margin: 0px 0px 16px 0px !important; }\n#mailpoet_form_1 p.mailpoet_form_paragraph.last { margin-bottom: 5px; }\n#mailpoet_form_1 .mailpoet_column_with_background { padding: 10px; }\n#mailpoet_form_1 .mailpoet_form_column:not(:first-child) { margin-left: 20px; }\n#mailpoet_form_1 .mailpoet_paragraph { font-size: 12px; line-height: 16px; color: #afafaf; }\n#mailpoet_form_1 .mailpoet_form .mailpoet_paragraph { margin-bottom: 12px; }\n#mailpoet_form_1 .mailpoet_segment_label, #mailpoet_form_1 .mailpoet_text_label, #mailpoet_form_1 .mailpoet_textarea_label, #mailpoet_form_1 .mailpoet_select_label, #mailpoet_form_1 .mailpoet_radio_label, #mailpoet_form_1 .mailpoet_checkbox_label, #mailpoet_form_1 .mailpoet_list_label, #mailpoet_form_1 .mailpoet_date_label { display: block; font-weight: normal; }\n#mailpoet_form_1 .mailpoet_text, #mailpoet_form_1 .mailpoet_textarea, #mailpoet_form_1 .mailpoet_select, #mailpoet_form_1 .mailpoet_date_month, #mailpoet_form_1 .mailpoet_date_day, #mailpoet_form_1 .mailpoet_date_year, #mailpoet_form_1 .mailpoet_date { display: block; }\n#mailpoet_form_1 .mailpoet_text, #mailpoet_form_1 .mailpoet_textarea { width: 200px; }\n#mailpoet_form_1 .mailpoet_checkbox { vertical-align: middle; }\n#mailpoet_form_1 .mailpoet_submit { background-color: white !important; color: black !important; }\n#mailpoet_form_1 .mailpoet_divider {  }\n#mailpoet_form_1 .mailpoet_message {  }\n#mailpoet_form_1 .mailpoet_form_loading { width: 30px; text-align: center; line-height: normal; }\n#mailpoet_form_1 .mailpoet_form_loading > span { width: 5px; height: 5px; background-color: #5b5b5b; }\n#mailpoet_form_1 .mailpoet_form_html a, #mailpoet_form_1 .mailpoet_form_iframe a { background-color: transparent; color: #ff6262; cursor: pointer; -webkit-text-decoration-skip-ink: all; text-decoration-skip-ink: all; text-decoration-thickness: 1px; text-underline-offset: 3px; }\n#mailpoet_form_1 #mailpoet_form_1 .mailpoet_checkbox { width: 16px; height: 16px; position: relative; top: 4px; }#mailpoet_form_1{border: 1px solid #54595f;border-radius: 16px;background: #1a1a1c;color: #ffffff;text-align: left;}#mailpoet_form_1 form.mailpoet_form {padding: 24px;}#mailpoet_form_1{width: 100%;}#mailpoet_form_1 .mailpoet_message {margin: 0; padding: 0 20px;}\n        #mailpoet_form_1 .mailpoet_validate_success {color: #00d084}\n        #mailpoet_form_1 input.parsley-success {color: #00d084}\n        #mailpoet_form_1 select.parsley-success {color: #00d084}\n        #mailpoet_form_1 textarea.parsley-success {color: #00d084}\n      \n        #mailpoet_form_1 .mailpoet_validate_error {color: #ff6900}\n        #mailpoet_form_1 input.parsley-error {color: #ff6900}\n        #mailpoet_form_1 select.parsley-error {color: #ff6900}\n        #mailpoet_form_1 textarea.textarea.parsley-error {color: #ff6900}\n        #mailpoet_form_1 .parsley-errors-list {color: #ff6900}\n        #mailpoet_form_1 .parsley-required {color: #ff6900}\n        #mailpoet_form_1 .parsley-custom-error-message {color: #ff6900}\n      #mailpoet_form_1 .mailpoet_paragraph.last {margin-bottom: 0} @media (max-width: 500px) {#mailpoet_form_1 {background: #1a1a1c;}} @media (min-width: 500px) {#mailpoet_form_1 .last .mailpoet_paragraph:last-child {margin-bottom: 0}}  @media (max-width: 500px) {#mailpoet_form_1 .mailpoet_form_column:last-child .mailpoet_paragraph:last-child {margin-bottom: 0}} \n    <\/style>\n\n    <form\n      target=\"_self\"\n      method=\"post\"\n      action=\"https:\/\/designcompass.org\/wp-admin\/admin-post.php?action=mailpoet_subscription_form\"\n      class=\"mailpoet_form mailpoet_form_form mailpoet_form_html\"\n      novalidate\n      data-delay=\"\"\n      data-exit-intent-enabled=\"\"\n      data-trigger-mode=\"\"\n      data-click-trigger-selector=\"\"\n      data-font-family=\"\"\n      data-cookie-expiration-time=\"\"\n    >\n      <input type=\"hidden\" name=\"data[form_id]\" value=\"1\" \/>\n      <input type=\"hidden\" name=\"token\" value=\"1596f10373\" \/>\n      <input type=\"hidden\" name=\"api_version\" value=\"v1\" \/>\n      <input type=\"hidden\" name=\"endpoint\" value=\"subscribers\" \/>\n      <input type=\"hidden\" name=\"mailpoet_method\" value=\"subscribe\" \/>\n\n      <label class=\"mailpoet_hp_email_label\" style=\"display: none !important;\">Please leave this field empty<input type=\"email\" name=\"data[email]\"\/><\/label><h2 class=\"mailpoet-heading  mailpoet-has-font-size\" style=\"text-align: left; color: #ffffff; font-size: 24px; line-height: 1.4\"><span style=\"font-family:\" data-font=\"\" class=\"mailpoet-has-font\"><strong>\ub514\uc790\uc778 \ub098\uce68\ubc18 \ub274\uc2a4\ub808\ud130<\/strong><\/span><\/h2>\n<div class=\"mailpoet_paragraph \"><style>input[name=\"data[form_field_MjZhN2MxMDVmNmI2X2VtYWls]\"]::placeholder{color:#ffffff;opacity: 1;}<\/style><input type=\"email\" autocomplete=\"email\" class=\"mailpoet_text\" id=\"form_email_1\" name=\"data[form_field_MjZhN2MxMDVmNmI2X2VtYWls]\" title=\"\uc774\uba54\uc77c \uc8fc\uc18c\" value=\"\" style=\"width:100%;box-sizing:border-box;background-color:#212123;border-style:solid;border-radius:8px !important;border-width:1px;border-color:#3d3d41;padding:12px;margin: 0 auto 0 0;font-size:13px;line-height:1.5;height:auto;color:#ffffff;\" data-automation-id=\"form_email\"  placeholder=\"\uc774\uba54\uc77c \uc8fc\uc18c *\" aria-label=\"\uc774\uba54\uc77c \uc8fc\uc18c *\" data-parsley-errors-container=\".mailpoet_error_3f8bv\" data-parsley-required=\"true\" required aria-required=\"true\" data-parsley-minlength=\"6\" data-parsley-maxlength=\"150\" data-parsley-type-message=\"This value should be a valid email.\" data-parsley-required-message=\"This field is required.\"\/><span class=\"mailpoet_error_3f8bv\"><\/span><\/div>\n<div class=\"mailpoet_paragraph \"><fieldset><input type=\"hidden\" value=\"1\"  name=\"data[cf_1]\" \/><label class=\"mailpoet_checkbox_label\" for=\"mailpoet_checkbox_1\" style=\"font-size: 13px;line-height: 1.2;\"><input type=\"checkbox\" class=\"mailpoet_checkbox\" id=\"mailpoet_checkbox_1\" name=\"data[cf_1]\" value=\"1\" data-parsley-errors-container=\".mailpoet_error_htyn5\" data-parsley-required=\"true\" required aria-required=\"true\" data-parsley-required-message=\"This field is required.\" data-parsley-group=\"custom_field_1\" \/> (\ud544\uc218)\uc774\uc6a9\uc57d\uad00, \uac1c\uc778\uc815\ubcf4\ucc98\ub9ac\ubc29\uce68\uc5d0 \ub3d9\uc758\ud569\ub2c8\ub2e4.<\/label><\/fieldset><span class=\"mailpoet_error_htyn5\"><\/span><\/div>\n<div class=\"mailpoet_paragraph \"><fieldset><input type=\"hidden\" value=\"1\"  name=\"data[cf_2]\" \/><label class=\"mailpoet_checkbox_label\" for=\"mailpoet_checkbox_2\" style=\"font-size: 13px;line-height: 1.2;\"><input type=\"checkbox\" class=\"mailpoet_checkbox\" id=\"mailpoet_checkbox_2\" name=\"data[cf_2]\" value=\"1\" data-parsley-errors-container=\".mailpoet_error_1yvfp\" data-parsley-required=\"true\" required aria-required=\"true\" data-parsley-required-message=\"This field is required.\" data-parsley-group=\"custom_field_2\" \/> (\ud544\uc218)\uad11\uace0\uc131 \uc815\ubcf4 \uc218\uc2e0\uc5d0 \ub3d9\uc758\ud569\ub2c8\ub2e4<\/label><\/fieldset><span class=\"mailpoet_error_1yvfp\"><\/span><\/div>\n<div class=\"mailpoet_paragraph \" style=\"font-size: 13px;line-height: 1.2;\"><a style=\"font-size:12px;color: #afafaf;text-decoration:underline\" href=\"https:\/\/designcompass.org\/terms-of-service\">\uc774\uc6a9\uc57d\uad00<\/a>  <a style=\"font-size:12px;color: #afafaf;text-decoration:underline\" href=\"https:\/\/designcompass.org\/privacy-policy\">\uac1c\uc778\uc815\ubcf4\ucc98\ub9ac\ubc29\uce68<\/a>   <a style=\"font-size:12px;color: #afafaf;text-decoration:underline\" href=\"https:\/\/designcompass.org\/marketing-agreement\">\ub9c8\ucf00\ud305\uc218\uc2e0\ub3d9\uc758<\/a><\/div>\n<div class=\"mailpoet_paragraph \"><input type=\"submit\" class=\"mailpoet_submit\" value=\"\ub274\uc2a4\ub808\ud130 \uad6c\ub3c5\" data-automation-id=\"subscribe-submit-button\" style=\"width:100%;box-sizing:border-box;background-color:#000000;border-style:solid;border-radius:40px !important;border-width:0px;border-color:#313131;padding:16px;margin: 0 auto 0 0;font-size:NaN;line-height:1.5;height:auto;color:#ffffff;font-weight:bold;\" \/><span class=\"mailpoet_form_loading\"><span class=\"mailpoet_bounce1\"><\/span><span class=\"mailpoet_bounce2\"><\/span><span class=\"mailpoet_bounce3\"><\/span><\/span><\/div>\n\n      <div class=\"mailpoet_message\">\n        <p class=\"mailpoet_validate_success\"\n                style=\"display:none;\"\n                >\uc815\uc0c1\uc801\uc778 \uc8fc\uc18c\uc778\uc9c0 \ud655\uc778\ud558\ub294 \uc774\uba54\uc77c\uc744 \ubcf4\ub0c8\uc2b5\ub2c8\ub2e4. \ubc1b\uc740 \uc774\uba54\uc77c\uc5d0\uc11c &#039;\ud65c\uc131\ud654&#039; \ubc84\ud2bc\uc744 \ub20c\ub7ec\uc8fc\uc138\uc694.\n        <\/p>\n        <p class=\"mailpoet_validate_error\"\n                style=\"display:none;\"\n                >        <\/p>\n      <\/div>\n    <\/form>\n\n      <\/div>\n\n  \n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4130900524608986\" crossorigin=\"anonymous\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block\" data-ad-format=\"autorelaxed\" data-ad-client=\"ca-pub-4130900524608986\" data-ad-slot=\"2908097030\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">\ube44\uc2b7\ud55c \uae00<\/h2>\n\n\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">\ucd5c\uadfc \uae00<\/h2>\n\n\n","protected":false},"excerpt":{"rendered":"<p>\uc5d0\uc5b4\ube44\uc564\ube44\uac00 \uaca8\uc6b8\uc744 \ub9de\uc544 \uc0c8\ub85c\uc6b4 \uae30\ub2a5\uc744 \uc120\ubcf4\uc785\ub2c8\ub2e4. \uac1c\uc131 \ub118\uce58\ub294 \ub3c5\ud2b9\ud55c \uc219\uc18c\ub97c \uc18c\uac1c\ud558\ub294 \uc5d0\uc5b4\ube44\uc564\ube44\uc5d0\uc11c \ubb34\uc5c7\uc744 \uc120\ud0dd\ud574\uc57c\ud560\uc9c0 \uc5b4\ub824\uc6cc\ud558\ub294 \uc0ac\ub78c\ub4e4\uc744 \uc704\ud55c \uc0c8\ub85c\uc6b4 \uae30\ub2a5\uc744 \uc81c\uacf5\ud569\ub2c8\ub2e4. \uc0ac\uc6a9\uc790\uac00 \uac8c\uc2a4\ud2b8\uc640 \uc219\uc18c\uc5d0 \uad00\ud574 \ub354 \ubbff\uc744\ub9cc\ud55c \uc815\ubcf4\ub97c \uc5bb\uc744 \uc218 \uc788\uace0 \ud638\uc2a4\ud2b8\ub294 \uc27d\uace0 \ud3b8\ud558\uac8c \uc815\ubcf4\ub97c \ub4f1\ub85d\ud558\uace0 \uad00\ub9ac\ud560 \uc218 \uc788\uac8c \ubc14\ub01d\ub2c8\ub2e4. \uc5c4\uaca9\ud55c \uae30\uc900\uc73c\ub85c \uc120\uc815\ud55c \uc219\uc18c\uc778 \u2018Guest favorite\u2019, \uc219\uc18c \ud488\uc9c8\uc744 \ub354 \uc790\uc138\ud788 \ud655\uc778\ud560 \uc218 \uc788\ub294 \uac1c\uc120\ub41c \ud6c4\uae30, \ud638\uc2a4\ud2b8\ub97c [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19507,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4,621],"tags":[69,185,370,377,467,596,597,717,758,763],"class_list":["post-19502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-service","tag-69","tag-185","tag-ui","tag-ux","tag-ui-ux","tag-interaction","tag-597","tag-717","tag-758","tag-763"],"acf":[],"jetpack_featured_media_url":"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/airbnb-23-winter-01.png","publishpress_future_action":{"enabled":false,"date":"2026-05-21 06:11:58","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/posts\/19502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/comments?post=19502"}],"version-history":[{"count":0,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/posts\/19502\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/media\/19507"}],"wp:attachment":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/media?parent=19502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/categories?post=19502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/tags?post=19502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}