{"id":19396,"date":"2023-11-02T10:19:03","date_gmt":"2023-11-02T01:19:03","guid":{"rendered":"https:\/\/designcompass.org\/?p=19396"},"modified":"2023-11-02T10:19:04","modified_gmt":"2023-11-02T01:19:04","slug":"internet-artifact","status":"publish","type":"post","link":"https:\/\/designcompass.org\/en\/2023\/11\/02\/internet-artifact\/","title":{"rendered":"Internet Artifacts: Modern Fire Explore the fascinating history of the Internet"},"content":{"rendered":"\n<p>internet artifact\ub294 Neal.Fun \ud504\ub85c\uc81d\ud2b8 \uc911 \ud558\ub098\ub85c \uc778\ud130\ub137 \uc720\ubb3c\uc744 \ubaa8\uc740 \uc6f9\uc0ac\uc774\ud2b8\uc785\ub2c8\ub2e4.<\/p>\n\n\n\n<p>1977\ub144 \ub124\ud2b8\uc6cc\ud06c\ub85c \uc5f0\uacb0\ub41c 111\uac1c\uc758 \ucef4\ud4e8\ud130 \ub2e8\ub9d0\uae30\ub85c \uad6c\uc131\ub41c \uc778\ud130\ub137\uc758 \uc804\uc2e0\uc778 ARPNET\uc758 \uc9c0\ub3c4, Digital Equipment Corporation\uc758 \ub9c8\ucf00\ud305 \uad00\ub9ac\uc790 Gary Thuerk\uc774 \ubcf4\ub0b8 \ucd5c\ucd08\uc758 \uc2a4\ud338 \uc774\uba54\uc77c, 1982\ub144 \ucd5c\ucd08\ub85c \uc4f0\uc778 \ud83d\ude42 \uc6c3\ub294 \ud45c\uc815, \ucd5c\ucd08\uc758 MP3\ud30c\uc77c\uc778 \uc218\uc794 \ubca0\uac00\uc758 \u2018Tom\u2019s Dinner\u2019 \ub4f1 \uc778\ud130\ub137 \uc138\uacc4\uc758 \uc218\ub9ce\uc740 \ucd5c\ucd08\uc758 \uae30\ub85d\ub4e4\uc774 \ub2f4\uacbc\uc2b5\ub2c8\ub2e4.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-03-3-1024x1024.png\" alt=\"\" class=\"wp-image-19422\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-03-3-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-03-3-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-03-3-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-03-3-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-03-3-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-03-3-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-03-3-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-03-3-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-03-3-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-03-3-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-03-3-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-03-3.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83d\udc41\ufe0f&nbsp;\ub514\uc790\uc774\ub108\uc758 \ub208<\/h3>\n\n\n\n<p>IT \ubd84\uc57c\uc758 \ub514\uc790\uc774\ub108\ub85c\uc11c \ud765\ubbf8\ub85c\uc6b4 \uc720\ubb3c\uc774 \ud55c\uac00\ub4dd\uc785\ub2c8\ub2e4. 1990\ub144 12\uc6d4 \ucd5c\ucd08\ub85c \ub9cc\ub4e4\uc5b4\uc9c4 <a href=\"http:\/\/Info.cern.ch\">Info.cern.ch<\/a>\uc740 \ud558\uc774\ud37c\ud14d\uc2a4\ud2b8\uc640 \uc6f9 \uc11c\ubc84 \uc124\uc815 \uc9c0\uce68\uc744 \ud3ec\ud568\ud574 WWW \ud504\ub85c\uc81d\ud2b8\uc5d0 \uad00\ud55c \uc790\uc138\ud55c \ub0b4\uc6a9\uc744 \ub2f4\uc558\uc2b5\ub2c8\ub2e4. \ud300 \ubc84\ub108\uc2a4 \ub9ac\ub294 WorldWideWeb\uc774\ub77c\ub294 \ucd5c\ucd08\uc758 \uc6f9 \ube0c\ub77c\uc6b0\uc800\ub97c \ub9cc\ub4e4\uc5c8\uace0 NeXT \ucef4\ud4e8\ud130\ub97c \uc11c\ubc84\ub85c \uccab \ubc88\uc9f8 \uc6f9\uc0ac\uc774\ud2b8\ub97c \ud638\uc2a4\ud305\ud588\uc2b5\ub2c8\ub2e4.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-01-2-1024x768.png\" alt=\"\" class=\"wp-image-19410\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-01-2-1024x768.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-01-2-300x225.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-01-2-768x576.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-01-2-1536x1152.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-01-2-16x12.png 16w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-01-2-924x693.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-01-2-671x503.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-01-2-1320x990.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-01-2-600x450.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-01-2.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\ucd5c\ucd08\uc758 \uc6f9 \uc0ac\uc9c4\uc740 Cern \uc9c1\uc6d0\uc774 \uacb0\uc131\ud55c \uc5ec\uc131 \ubc34\ub4dc Les Horribles Cernettes\uc758 \uc0ac\uc9c4\uc774\uc5c8\uc2b5\ub2c8\ub2e4. \ubb38\uc11c\ub97c \uc800\uc7a5\ud558\uae30 \uc704\ud55c \ud50c\ub7ab\ud3fc\uc5d0\uc11c \ubbf8\ub514\uc5b4\ub97c \ub2f4\ub294 \ud50c\ub7ab\ud3fc\uc73c\ub85c \ubcc0\ud558\uac8c \ub9cc\ub4e0 \uc0ac\uac74 \uc911 \ud558\ub098\ub77c\uace0 \ud588\uc2b5\ub2c8\ub2e4.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-04-1-1024x1024.png\" alt=\"\" class=\"wp-image-19411\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-04-1-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-04-1-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-04-1-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-04-1-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-04-1-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-04-1-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-04-1-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-04-1-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-04-1-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-04-1-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-04-1-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-04-1.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\ucd5c\ucd08\uc758 \uc628\ub77c\uc778 \ubc30\ub2ec \uc6f9\uc0ac\uc774\ud2b8\ub294 1994\ub144 \ud53c\uc790\ud5db\uc5d0\uc11c \ub9cc\ub4e0 PizzaNet\uc774\uc5c8\uc2b5\ub2c8\ub2e4. \uc0b0\ud0c0 \ud06c\ub8e8\uc988 \uc9c0\uc5ed\uc5d0\uc11c\ub9cc \uc0ac\uc6a9\ud560 \uc218 \uc788\uc5c8\uc2b5\ub2c8\ub2e4. \ub300\ud615 \ud398\ud37c\ub85c\ub2c8\uc640 \ubc84\uc12f \ud53c\uc790 \ub4f1\uc744 \ud310\ub9e4\ud588\uc2b5\ub2c8\ub2e4. \uccab\ubc88\uc9f8 \uc544\ub9c8\uc874 \uc8fc\ubb38\uc740 1995\ub144 Douglas Hofstadter\uc758 \ucc45 Fluid Concpets and Creative Analogies\uc774\uc5c8\uc2b5\ub2c8\ub2e4. \uc774 \ucc45\uc744 \uc8fc\ubb38\ud55c Wainwright\ub294 \ubb34\ub8cc\uc778 \uc904 \uc54c\uc558\ub294\ub370 \uc2e0\uc6a9\uce74\ub4dc\ub85c \uacb0\uc81c\ub418\uc5b4\uc11c \ub3c4\ub451 \ub9de\uc558\ub2e4\uace0 \ud588\uc5c8\uc2b5\ub2c8\ub2e4.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-07-1-1024x1024.png\" alt=\"\" class=\"wp-image-19412\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-07-1-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-07-1-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-07-1-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-07-1-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-07-1-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-07-1-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-07-1-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-07-1-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-07-1-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-07-1-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-07-1-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-07-1.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-08-1-1024x1024.png\" alt=\"\" class=\"wp-image-19413\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-08-1-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-08-1-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-08-1-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-08-1-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-08-1-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-08-1-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-08-1-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-08-1-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-08-1-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-08-1-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-08-1-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-08-1.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\uc774\uc678\uc5d0\ub3c4 \ucd5c\ucd08\uc758 \ubc08, \ucd5c\ucd08\uc758 \uc774\ubaa8\ud2f0\ucf58, \ucd5c\ucd08\uc758 \uc704\ud0a4\ud53c\ub514\uc544 \ub4f1 \ud765\ubbf8\ub85c\uc6b4 \uc774\uc57c\uae30\uac00 \uac00\ub4dd\ud569\ub2c8\ub2e4. \ub514\uc9c0\ud138 \ud504\ub85c\ub355\ud2b8\ub97c \ub9cc\ub4dc\ub294 \uc0ac\ub78c\uc774\ub77c\uba74 \uaf2d \uc0b4\ud3b4\ubcf4\uc138\uc694.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-05-1024x1024.png\" alt=\"\" class=\"wp-image-19415\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-05-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-05-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-05-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-05-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-05-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-05-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-05-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-05-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-05-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-05-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-05-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-05.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-09-1-1024x1024.png\" alt=\"\" class=\"wp-image-19414\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-09-1-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-09-1-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-09-1-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-09-1-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-09-1-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-09-1-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-09-1-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-09-1-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-09-1-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-09-1-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-09-1-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-09-1.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-10-2-1024x1024.png\" alt=\"\" class=\"wp-image-19418\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-10-2-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-10-2-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-10-2-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-10-2-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-10-2-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-10-2-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-10-2-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-10-2-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-10-2-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-10-2-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-10-2-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-10-2.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-11-1-1024x1024.png\" alt=\"\" class=\"wp-image-19417\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-11-1-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-11-1-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-11-1-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-11-1-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-11-1-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-11-1-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-11-1-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-11-1-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-11-1-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-11-1-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-11-1-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-11-1.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">\ub354 \ubcf4\uae30 \ubc0f \ucd9c\ucc98<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/neal.fun\/internet-artifacts\/\">https:\/\/neal.fun\/internet-artifacts\/<\/a><\/li>\n<\/ul>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n  \n  \n  <div class=\"\n    mailpoet_form_popup_overlay\n      \"><\/div>\n  <div\n    id=\"mailpoet_form_1\"\n    class=\"\n      mailpoet_form\n      mailpoet_form_html\n      mailpoet_form_position_\n      mailpoet_form_animation_\n    \"\n      >\n\n    <style type=\"text\/css\">\n     #mailpoet_form_1 .mailpoet_form {  }\n#mailpoet_form_1 form { margin-bottom: 0; }\n#mailpoet_form_1 h1.mailpoet-heading { margin: 0px 0px 16px 0px; }\n#mailpoet_form_1 .mailpoet_form .mailpoet-has-font-size { margin: 0px 0px 16px 0px !important; }\n#mailpoet_form_1 p.mailpoet_form_paragraph.last { margin-bottom: 5px; }\n#mailpoet_form_1 .mailpoet_column_with_background { padding: 10px; }\n#mailpoet_form_1 .mailpoet_form_column:not(:first-child) { margin-left: 20px; }\n#mailpoet_form_1 .mailpoet_paragraph { font-size: 12px; line-height: 16px; color: #afafaf; }\n#mailpoet_form_1 .mailpoet_form .mailpoet_paragraph { margin-bottom: 12px; }\n#mailpoet_form_1 .mailpoet_segment_label, #mailpoet_form_1 .mailpoet_text_label, #mailpoet_form_1 .mailpoet_textarea_label, #mailpoet_form_1 .mailpoet_select_label, #mailpoet_form_1 .mailpoet_radio_label, #mailpoet_form_1 .mailpoet_checkbox_label, #mailpoet_form_1 .mailpoet_list_label, #mailpoet_form_1 .mailpoet_date_label { display: block; font-weight: normal; }\n#mailpoet_form_1 .mailpoet_text, #mailpoet_form_1 .mailpoet_textarea, #mailpoet_form_1 .mailpoet_select, #mailpoet_form_1 .mailpoet_date_month, #mailpoet_form_1 .mailpoet_date_day, #mailpoet_form_1 .mailpoet_date_year, #mailpoet_form_1 .mailpoet_date { display: block; }\n#mailpoet_form_1 .mailpoet_text, #mailpoet_form_1 .mailpoet_textarea { width: 200px; }\n#mailpoet_form_1 .mailpoet_checkbox { vertical-align: middle; }\n#mailpoet_form_1 .mailpoet_submit { background-color: white !important; color: black !important; }\n#mailpoet_form_1 .mailpoet_divider {  }\n#mailpoet_form_1 .mailpoet_message {  }\n#mailpoet_form_1 .mailpoet_form_loading { width: 30px; text-align: center; line-height: normal; }\n#mailpoet_form_1 .mailpoet_form_loading > span { width: 5px; height: 5px; background-color: #5b5b5b; }\n#mailpoet_form_1 .mailpoet_form_html a, #mailpoet_form_1 .mailpoet_form_iframe a { background-color: transparent; color: #ff6262; cursor: pointer; -webkit-text-decoration-skip-ink: all; text-decoration-skip-ink: all; text-decoration-thickness: 1px; text-underline-offset: 3px; }\n#mailpoet_form_1 #mailpoet_form_1 .mailpoet_checkbox { width: 16px; height: 16px; position: relative; top: 4px; }#mailpoet_form_1{border: 1px solid #54595f;border-radius: 16px;background: #1a1a1c;color: #ffffff;text-align: left;}#mailpoet_form_1 form.mailpoet_form {padding: 24px;}#mailpoet_form_1{width: 100%;}#mailpoet_form_1 .mailpoet_message {margin: 0; padding: 0 20px;}\n        #mailpoet_form_1 .mailpoet_validate_success {color: #00d084}\n        #mailpoet_form_1 input.parsley-success {color: #00d084}\n        #mailpoet_form_1 select.parsley-success {color: #00d084}\n        #mailpoet_form_1 textarea.parsley-success {color: #00d084}\n      \n        #mailpoet_form_1 .mailpoet_validate_error {color: #ff6900}\n        #mailpoet_form_1 input.parsley-error {color: #ff6900}\n        #mailpoet_form_1 select.parsley-error {color: #ff6900}\n        #mailpoet_form_1 textarea.textarea.parsley-error {color: #ff6900}\n        #mailpoet_form_1 .parsley-errors-list {color: #ff6900}\n        #mailpoet_form_1 .parsley-required {color: #ff6900}\n        #mailpoet_form_1 .parsley-custom-error-message {color: #ff6900}\n      #mailpoet_form_1 .mailpoet_paragraph.last {margin-bottom: 0} @media (max-width: 500px) {#mailpoet_form_1 {background: #1a1a1c;}} @media (min-width: 500px) {#mailpoet_form_1 .last .mailpoet_paragraph:last-child {margin-bottom: 0}}  @media (max-width: 500px) {#mailpoet_form_1 .mailpoet_form_column:last-child .mailpoet_paragraph:last-child {margin-bottom: 0}} \n    <\/style>\n\n    <form\n      target=\"_self\"\n      method=\"post\"\n      action=\"https:\/\/designcompass.org\/wp-admin\/admin-post.php?action=mailpoet_subscription_form\"\n      class=\"mailpoet_form mailpoet_form_form mailpoet_form_html\"\n      novalidate\n      data-delay=\"\"\n      data-exit-intent-enabled=\"\"\n      data-trigger-mode=\"\"\n      data-click-trigger-selector=\"\"\n      data-font-family=\"\"\n      data-cookie-expiration-time=\"\"\n    >\n      <input type=\"hidden\" name=\"data[form_id]\" value=\"1\" \/>\n      <input type=\"hidden\" name=\"token\" value=\"1596f10373\" \/>\n      <input type=\"hidden\" name=\"api_version\" value=\"v1\" \/>\n      <input type=\"hidden\" name=\"endpoint\" value=\"subscribers\" \/>\n      <input type=\"hidden\" name=\"mailpoet_method\" value=\"subscribe\" \/>\n\n      <label class=\"mailpoet_hp_email_label\" style=\"display: none !important;\">Please leave this field empty<input type=\"email\" name=\"data[email]\"\/><\/label><h2 class=\"mailpoet-heading  mailpoet-has-font-size\" style=\"text-align: left; color: #ffffff; font-size: 24px; line-height: 1.4\"><span style=\"font-family:\" data-font=\"\" class=\"mailpoet-has-font\"><strong>\ub514\uc790\uc778 \ub098\uce68\ubc18 \ub274\uc2a4\ub808\ud130<\/strong><\/span><\/h2>\n<div class=\"mailpoet_paragraph \"><style>input[name=\"data[form_field_MjZhN2MxMDVmNmI2X2VtYWls]\"]::placeholder{color:#ffffff;opacity: 1;}<\/style><input type=\"email\" autocomplete=\"email\" class=\"mailpoet_text\" id=\"form_email_1\" name=\"data[form_field_MjZhN2MxMDVmNmI2X2VtYWls]\" title=\"\uc774\uba54\uc77c \uc8fc\uc18c\" value=\"\" style=\"width:100%;box-sizing:border-box;background-color:#212123;border-style:solid;border-radius:8px !important;border-width:1px;border-color:#3d3d41;padding:12px;margin: 0 auto 0 0;font-size:13px;line-height:1.5;height:auto;color:#ffffff;\" data-automation-id=\"form_email\"  placeholder=\"\uc774\uba54\uc77c \uc8fc\uc18c *\" aria-label=\"\uc774\uba54\uc77c \uc8fc\uc18c *\" data-parsley-errors-container=\".mailpoet_error_1hjgr\" data-parsley-required=\"true\" required aria-required=\"true\" data-parsley-minlength=\"6\" data-parsley-maxlength=\"150\" data-parsley-type-message=\"This value should be a valid email.\" data-parsley-required-message=\"This field is required.\"\/><span class=\"mailpoet_error_1hjgr\"><\/span><\/div>\n<div class=\"mailpoet_paragraph \"><fieldset><input type=\"hidden\" value=\"1\"  name=\"data[cf_1]\" \/><label class=\"mailpoet_checkbox_label\" for=\"mailpoet_checkbox_1\" style=\"font-size: 13px;line-height: 1.2;\"><input type=\"checkbox\" class=\"mailpoet_checkbox\" id=\"mailpoet_checkbox_1\" name=\"data[cf_1]\" value=\"1\" data-parsley-errors-container=\".mailpoet_error_1b4td\" data-parsley-required=\"true\" required aria-required=\"true\" data-parsley-required-message=\"This field is required.\" data-parsley-group=\"custom_field_1\" \/> (\ud544\uc218)\uc774\uc6a9\uc57d\uad00, \uac1c\uc778\uc815\ubcf4\ucc98\ub9ac\ubc29\uce68\uc5d0 \ub3d9\uc758\ud569\ub2c8\ub2e4.<\/label><\/fieldset><span class=\"mailpoet_error_1b4td\"><\/span><\/div>\n<div class=\"mailpoet_paragraph \"><fieldset><input type=\"hidden\" value=\"1\"  name=\"data[cf_2]\" \/><label class=\"mailpoet_checkbox_label\" for=\"mailpoet_checkbox_2\" style=\"font-size: 13px;line-height: 1.2;\"><input type=\"checkbox\" class=\"mailpoet_checkbox\" id=\"mailpoet_checkbox_2\" name=\"data[cf_2]\" value=\"1\" data-parsley-errors-container=\".mailpoet_error_1n71g\" data-parsley-required=\"true\" required aria-required=\"true\" data-parsley-required-message=\"This field is required.\" data-parsley-group=\"custom_field_2\" \/> (\ud544\uc218)\uad11\uace0\uc131 \uc815\ubcf4 \uc218\uc2e0\uc5d0 \ub3d9\uc758\ud569\ub2c8\ub2e4<\/label><\/fieldset><span class=\"mailpoet_error_1n71g\"><\/span><\/div>\n<div class=\"mailpoet_paragraph \" style=\"font-size: 13px;line-height: 1.2;\"><a style=\"font-size:12px;color: #afafaf;text-decoration:underline\" href=\"https:\/\/designcompass.org\/terms-of-service\">\uc774\uc6a9\uc57d\uad00<\/a>  <a style=\"font-size:12px;color: #afafaf;text-decoration:underline\" href=\"https:\/\/designcompass.org\/privacy-policy\">\uac1c\uc778\uc815\ubcf4\ucc98\ub9ac\ubc29\uce68<\/a>   <a style=\"font-size:12px;color: #afafaf;text-decoration:underline\" href=\"https:\/\/designcompass.org\/marketing-agreement\">\ub9c8\ucf00\ud305\uc218\uc2e0\ub3d9\uc758<\/a><\/div>\n<div class=\"mailpoet_paragraph \"><input type=\"submit\" class=\"mailpoet_submit\" value=\"\ub274\uc2a4\ub808\ud130 \uad6c\ub3c5\" data-automation-id=\"subscribe-submit-button\" style=\"width:100%;box-sizing:border-box;background-color:#000000;border-style:solid;border-radius:40px !important;border-width:0px;border-color:#313131;padding:16px;margin: 0 auto 0 0;font-size:NaN;line-height:1.5;height:auto;color:#ffffff;font-weight:bold;\" \/><span class=\"mailpoet_form_loading\"><span class=\"mailpoet_bounce1\"><\/span><span class=\"mailpoet_bounce2\"><\/span><span class=\"mailpoet_bounce3\"><\/span><\/span><\/div>\n\n      <div class=\"mailpoet_message\">\n        <p class=\"mailpoet_validate_success\"\n                style=\"display:none;\"\n                >\uc815\uc0c1\uc801\uc778 \uc8fc\uc18c\uc778\uc9c0 \ud655\uc778\ud558\ub294 \uc774\uba54\uc77c\uc744 \ubcf4\ub0c8\uc2b5\ub2c8\ub2e4. \ubc1b\uc740 \uc774\uba54\uc77c\uc5d0\uc11c &#039;\ud65c\uc131\ud654&#039; \ubc84\ud2bc\uc744 \ub20c\ub7ec\uc8fc\uc138\uc694.\n        <\/p>\n        <p class=\"mailpoet_validate_error\"\n                style=\"display:none;\"\n                >        <\/p>\n      <\/div>\n    <\/form>\n\n      <\/div>\n\n  \n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4130900524608986\" crossorigin=\"anonymous\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block\" data-ad-format=\"autorelaxed\" data-ad-client=\"ca-pub-4130900524608986\" data-ad-slot=\"2908097030\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">\ube44\uc2b7\ud55c \uae00<\/h2>\n\n\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">\ucd5c\uadfc \uae00<\/h2>\n\n\n","protected":false},"excerpt":{"rendered":"<p>internet artifact\ub294 Neal.Fun \ud504\ub85c\uc81d\ud2b8 \uc911 \ud558\ub098\ub85c \uc778\ud130\ub137 \uc720\ubb3c\uc744 \ubaa8\uc740 \uc6f9\uc0ac\uc774\ud2b8\uc785\ub2c8\ub2e4. 1977\ub144 \ub124\ud2b8\uc6cc\ud06c\ub85c \uc5f0\uacb0\ub41c 111\uac1c\uc758 \ucef4\ud4e8\ud130 \ub2e8\ub9d0\uae30\ub85c \uad6c\uc131\ub41c \uc778\ud130\ub137\uc758 \uc804\uc2e0\uc778 ARPNET\uc758 \uc9c0\ub3c4, Digital Equipment Corporation\uc758 \ub9c8\ucf00\ud305 \uad00\ub9ac\uc790 Gary Thuerk\uc774 \ubcf4\ub0b8 \ucd5c\ucd08\uc758 \uc2a4\ud338 \uc774\uba54\uc77c, 1982\ub144 \ucd5c\ucd08\ub85c \uc4f0\uc778 \ud83d\ude42 \uc6c3\ub294 \ud45c\uc815, \ucd5c\ucd08\uc758 MP3\ud30c\uc77c\uc778 \uc218\uc794 \ubca0\uac00\uc758 \u2018Tom\u2019s Dinner\u2019 \ub4f1 \uc778\ud130\ub137 \uc138\uacc4\uc758 \uc218\ub9ce\uc740 \ucd5c\ucd08\uc758 \uae30\ub85d\ub4e4\uc774 \ub2f4\uacbc\uc2b5\ub2c8\ub2e4. \ud83d\udc41\ufe0f&nbsp;\ub514\uc790\uc774\ub108\uc758 \ub208 IT \ubd84\uc57c\uc758 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19398,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4,621],"tags":[69,185,370,377,467,596,597,717,758,763],"class_list":["post-19396","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-service","tag-69","tag-185","tag-ui","tag-ux","tag-ui-ux","tag-interaction","tag-597","tag-717","tag-758","tag-763"],"acf":[],"jetpack_featured_media_url":"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/11\/internet-artifact-01.png","publishpress_future_action":{"enabled":false,"date":"2026-05-21 05:04:05","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/posts\/19396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/comments?post=19396"}],"version-history":[{"count":0,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/posts\/19396\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/media\/19398"}],"wp:attachment":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/media?parent=19396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/categories?post=19396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/tags?post=19396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}