{"id":17873,"date":"2023-08-22T08:24:09","date_gmt":"2023-08-21T23:24:09","guid":{"rendered":"https:\/\/designcompass.org\/?p=17873"},"modified":"2023-08-22T08:24:12","modified_gmt":"2023-08-21T23:24:12","slug":"starfield","status":"publish","type":"post","link":"https:\/\/designcompass.org\/en\/2023\/08\/22\/starfield\/","title":{"rendered":"Starfield Coming Soon: Realistic and Fantastic Space Designs"},"content":{"rendered":"\n<p>\uc2a4\ud0c0\ud544\ub4dc\uac00 \ucd9c\uc2dc\ud569\ub2c8\ub2e4. \uc2a4\ud0c0\ud544\ub4dc\ub294 \uc5d8\ub354\uc2a4\ud06c\ub864, \ud3f4\uc544\uc6c3\uc744 \ub9cc\ub4e0 \ubca0\ub370\uc2a4\ub2e4\uac00 25\ub144\ub9cc\uc5d0 \uc0c8\ub86d\uac8c \ucd9c\uc2dc\ud558\ub294 IP\uc785\ub2c8\ub2e4. \ucd5c\ucd08 \uc544\uc774\ub514\uc5b4\ub294 \ud1a0\ub4dc \ud558\uc6cc\ub4dc\uac00 10\ub300 \ub54c \uc560\ud50c 2 \ucef4\ud4e8\ud130\ub85c \ub9cc\ub4e0 \uac8c\uc784\uc5d0\uc11c \uc2dc\uc791\ub410\ub2e4\uace0 \ud569\ub2c8\ub2e4. \uc2e4\uc81c \uac1c\ubc1c \ucc29\uc218\ub294 2017\ub144\ubd80\ud130 \uc2dc\uc791\ub410\uc73c\uba70 \uc5d1\uc2a4\ubc15\uc2a4 \ub3c5\uc810\uc73c\ub85c \uc5bc\ub9ac \uc5b5\uc138\uc2a4\ub294 9\uc6d4 1\uc77c\uc5d0 \uc5f4\ub9ac\uba70 9\uc6d4 6\uc77c\uc5d0 \uc815\uc2dd \ucd9c\uc2dc\ud569\ub2c8\ub2e4.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-03-1024x1024.png\" alt=\"\" class=\"wp-image-17878\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-03-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-03-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-03-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-03-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-03-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-03-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-03-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-03-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-03-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-03-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-03-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-03.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Starfield\u00a9Bethesda<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Starfield Official Gameplay Trailer\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/kfYEiTdsyas?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83d\udc41\ufe0f&nbsp;\ub514\uc790\uc774\ub108\uc758 \ub208<\/h3>\n\n\n\n<p>\ub290\uc2a8\ud55c \uc6b0\uc8fc \uc5ec\ud589\ubcf4\ub2e4\ub294 \ubc00\ub3c4 \ub192\uc740 \ud589\uc131 \ub4dc\ub77c\ub9c8\uac00 \ub420 \uac83\uc73c\ub85c \ubcf4\uc785\ub2c8\ub2e4. 4\uac1c\uc758 \ubcc4\uc744 \ud0d0\ud5d8\ud558\uba70 \uc0dd\uba85\uccb4, \uc790\uc6d0, \ubaa8\ud5d8\uc744 \uc990\uae38 \uc218 \uc788\uc2b5\ub2c8\ub2e4. \ub69c\ub837\ud55c \uac1c\uc131\uc744 \uac00\uc9c4 \ub3c4\uc2dc\uc640 \uc5f0\ud569\ub4e4\uc774 \uc788\uc73c\uba70 \ud50c\ub808\uc774\uc5b4\ub294 \uc790\uc2e0\ub9cc\uc758 \ubc30\uacbd\uc744 \uac00\uc9c4 \uce90\ub9ad\ud130\ub97c \ub9cc\ub4e4\uc5b4 \ud0d0\ud5d8\ud560 \uc218 \uc788\uc2b5\ub2c8\ub2e4. \ucc9c \uac1c\uac00 \ub118\ub294 \ubbf8\uc9c0\uc758 \uc138\uacc4\ub97c \ud0d0\ud5d8\ud558\uace0 \uc790\uc2e0\ub9cc\uc758 \uac70\uc8fc \uacf5\uac04\uc744 \ub9cc\ub4e4 \uc218\ub3c4 \uc788\uc2b5\ub2c8\ub2e4.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-09-1024x1024.png\" alt=\"\" class=\"wp-image-17875\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-09-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-09-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-09-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-09-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-09-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-09-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-09-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-09-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-09-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-09-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-09-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-09.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Starfield\u00a9Bethesda<\/figcaption><\/figure>\n\n\n\n<p>\ud604\uc2e4\uc801\uc778 \ub290\ub08c\uc758 \uc778\uac8c\uc784 \ub514\uc790\uc778\uacfc \ub808\ud2b8\ub85c\ud55c \uadf8\ub798\ud53d \ud45c\ud604\uc774 \uacb0\ud569\ub418\uc5b4 \uc775\uc219\ud558\uba74\uc11c \ubbf8\ub798\uc801\uc778 \ub290\ub08c\uc744 \uc90d\ub2c8\ub2e4. SF\uc801\uc778 \uc990\uac70\uc6c0\uacfc \ud604\uc2e4\uac10\uc758 \uade0\ud615\uc744 \ub9de\ucd94\uae30 \uc704\ud574 NASA\uc758 \ub370\uc774\ud130\ub97c \uc5f0\uad6c\ud588\uc2b5\ub2c8\ub2e4. \ud558\uc580 \ud45c\uba74\uc5d0 \ubd89\uc740 \ud3ec\uc778\ud2b8\ub97c \uc0ac\uc6a9\ud55c \ud45c\ud604\uc774 NASA\uc2a4\ub7fd\uc2b5\ub2c8\ub2e4. \ub354 \ud604\uc2e4\uc801\uc778 \ubb18\uc0ac\ub97c \uc704\ud574 \ud1a0\ub4dc \ud558\uc6cc\ub4dc\ub294 \uc77c\ub860 \uba38\uc2a4\ud06c\uc758 \uc2a4\ud398\uc774\uc2a4 X \ud504\ub85c\uadf8\ub7a8\uc744 \ud604\uc7a5 \uc870\uc0ac\ud558\uae30\ub3c4 \ud588\uc2b5\ub2c8\ub2e4.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"464\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/Starfield_LargeHero_FullDirect-1024x464.webp\" alt=\"\" class=\"wp-image-17876\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/Starfield_LargeHero_FullDirect-1024x464.webp 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/Starfield_LargeHero_FullDirect-300x136.webp 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/Starfield_LargeHero_FullDirect-768x348.webp 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/Starfield_LargeHero_FullDirect-18x8.webp 18w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/Starfield_LargeHero_FullDirect-924x419.webp 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/Starfield_LargeHero_FullDirect-671x304.webp 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/Starfield_LargeHero_FullDirect-600x272.webp 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/Starfield_LargeHero_FullDirect.webp 1121w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Starfield\u00a9Bethesda<\/figcaption><\/figure>\n\n\n\n<p>\ub9e4\ub825\uc801\uc778 \uc560\ub2c8\uba54\uc774\uc158\ub3c4 \uacf5\uac1c\ud588\uc2b5\ub2c8\ub2e4. \uad11\ub300\ud55c \uc6b0\uc8fc \uc18d The Settled Systems\uc758 3\uac1c \uc8fc\uc694 \ub3c4\uc2dc\ub97c \ud45c\ud604\ud558\ub294 \uc560\ub2c8\uba54\uc774\uc158\ub3c4 \uba4b\uc9d1\ub2c8\ub2e4. \ub208\ubd80\uc2e0 \uc218\ucc44\ud654\uc5d0 90\ub144\ub300 \uce74\uba54\ub77c \ud544\ud130\uac00 \ub080 \ub290\ub08c\uc774 \ubab0\uc785\uac10\uc744 \ub192\uc785\ub2c8\ub2e4.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Starfield: The Settled Systems - Supra Et Ultra\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/8Kj6wulHMsA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>\ubb3c\ub9ac\uc801\uc73c\ub85c \uc2a4\ud0c0\ud544\ub4dc\ub97c \ub290\ub084 \uc218 \uc788\ub294 \ubb3c\ub9ac\uc801 \uc694\uc18c\ub3c4 \uba4b\uc9d1\ub2c8\ub2e4. \ud2b9\ubcc4 \uc5d0\ub514\uc158\uc744 \uad6c\ub9e4\ud558\uba74 \ubc1b\uc744 \uc218 \uc788\ub294 \uc2dc\uacc4 \ucf00\uc774\uc2a4\ub294 \uc544\ud3f4\ub85c \uacc4\ud68d\uc5d0\uc11c \uc6d4\uc11d\uc744 \ub2f4\uc558\ub358 \ucee8\ud14c\uc774\ub108\ub97c \ubaa8\uc0ac\ud588\uc2b5\ub2c8\ub2e4. \uc2a4\ud0c0\ud544\ub4dc \ud55c\uc815\ud310 \ubb34\uc120 \ucee8\ud2b8\ub864\ub7ec\uc640 \ud5e4\ub4dc\uc14b\uc740 \uc774\ubbf8 \ub9e4\uc9c4\ub418\uc5c8\ub2e4\uace0 \ud558\ub124\uc694. \uc5d1\uc2a4\ubc15\uc2a4 \ubcf8\uccb4\uc5d0 \ubd99\uc600\ub2e4 \ub5c4 \uc218 \uc788\ub294 4~50\ub2ec\ub7ec\uc758 WRAP\uc740 \uc2a4\ud2f0\ucee4\uc640 \ub2e4\ub974\uac8c \ub450\uaebc\uc6b4 \uc18c\uc7ac\uc758 \uadf9\uc138\uc0ac\ub77c\uace0 \ud569\ub2c8\ub2e4. \uc5d0\ub514\uc158 \ub7a9\uc740 10\uc6d4 18\uc77c\uc5d0 \ucd9c\uc2dc\ud569\ub2c8\ub2e4.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-11-1024x1024.png\" alt=\"\" class=\"wp-image-17877\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-11-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-11-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-11-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-11-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-11-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-11-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-11-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-11-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-11-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-11-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-11-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-11.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Starfield\u00a9Bethesda<\/figcaption><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83d\udcd5&nbsp;\uc5d0\ub514\ud130 \ub178\ud2b8<\/h3>\n\n\n\n<p>\uac8c\uc784\uc774\uc57c\ub9d0\ub85c \uc885\ud569 \uc608\uc220\uc774\uc790 \uacbd\ud5d8\uc758 \ub05d\ud310\uc774\uc8e0. \uac04\ub9cc\uc5d0 \uc815\ub9d0 \ub69c\ub837\ud55c \uc790\uae30\ub9cc\uc758 \uc0c9\uc744 \uac00\uc9c4 \uba4b\uc9c4 \uc138\uacc4\ub97c \uc798 \uad6c\ud604\ud588\uc2b5\ub2c8\ub2e4. \uc2a4\ud0c0\ud544\ub4dc\ub294 \uc0ac\ub78c\ub4e4\uc774 \uacfc\ud558\uac8c \uae30\ub300\ud558\uc9c0 \uc54a\uac8c \uc624\ud788\ub824 \uae30\ub300\uce58\ub97c \ub0ae\ucd94\ub824\uace0 \ub178\ub825\ud558\ub124\uc694. \uacfc\ub300 \uad11\uace0\ub85c \ud06c\uac8c \uc5bb\uc5b4\ub9de\uc740 \uc0ac\uc774\ubc84\ud391\ud06c\ub098 \ubc30\ud2c0\ud544\ub4dc\uc758 \uc0ac\ub840\ub97c \ubc18\ubcf5\ud558\uc9c0 \uc54a\uc73c\ub824\ub294 \uac83\uc73c\ub85c \ubcf4\uc774\ub124\uc694. \ub85c\uace0, \uadf8\ub798\ud53d \ub514\uc790\uc778, \uad7f\uc988 \ub514\uc790\uc778\uae4c\uc9c0 \ub9e4\ub825\uc801\uc785\ub2c8\ub2e4. \ud558\ub8e8 \ube68\ub9ac \uacbd\ud5d8\ud574\ubcf4\uace0 \uc2f6\ub124\uc694.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-04-1024x1024.png\" alt=\"\" class=\"wp-image-17879\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-04-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-04-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-04-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-04-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-04-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-04-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-04-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-04-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-04-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-04-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-04-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-04.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Starfield\u00a9Bethesda<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-05-1024x1024.png\" alt=\"\" class=\"wp-image-17880\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-05-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-05-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-05-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-05-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-05-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-05-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-05-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-05-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-05-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-05-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-05-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-05.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Starfield\u00a9Bethesda<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-06-1024x1024.png\" alt=\"\" class=\"wp-image-17881\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-06-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-06-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-06-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-06-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-06-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-06-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-06-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-06-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-06-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-06-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-06-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-06.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Starfield\u00a9Bethesda<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-07-1-1024x1024.png\" alt=\"\" class=\"wp-image-17885\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-07-1-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-07-1-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-07-1-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-07-1-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-07-1-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-07-1-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-07-1-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-07-1-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-07-1-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-07-1-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-07-1-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-07-1.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Starfield\u00a9Bethesda<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-08-1024x1024.png\" alt=\"\" class=\"wp-image-17883\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-08-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-08-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-08-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-08-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-08-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-08-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-08-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-08-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-08-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-08-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-08-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-08.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Starfield\u00a9Bethesda<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-10-1024x1024.png\" alt=\"\" class=\"wp-image-17884\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-10-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-10-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-10-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-10-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-10-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-10-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-10-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-10-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-10-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-10-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-10-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-10.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Starfield\u00a9Bethesda<\/figcaption><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">\ub354 \ubcf4\uae30 \ubc0f \ucd9c\ucc98<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/bethesda.net\/ko\/game\/starfield\">https:\/\/bethesda.net\/ko\/game\/starfield<\/a><\/li>\n<\/ul>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n  \n  \n  <div class=\"\n    mailpoet_form_popup_overlay\n      \"><\/div>\n  <div\n    id=\"mailpoet_form_1\"\n    class=\"\n      mailpoet_form\n      mailpoet_form_html\n      mailpoet_form_position_\n      mailpoet_form_animation_\n    \"\n      >\n\n    <style type=\"text\/css\">\n     #mailpoet_form_1 .mailpoet_form {  }\n#mailpoet_form_1 form { margin-bottom: 0; }\n#mailpoet_form_1 h1.mailpoet-heading { margin: 0px 0px 16px 0px; }\n#mailpoet_form_1 .mailpoet_form .mailpoet-has-font-size { margin: 0px 0px 16px 0px !important; }\n#mailpoet_form_1 p.mailpoet_form_paragraph.last { margin-bottom: 5px; }\n#mailpoet_form_1 .mailpoet_column_with_background { padding: 10px; }\n#mailpoet_form_1 .mailpoet_form_column:not(:first-child) { margin-left: 20px; }\n#mailpoet_form_1 .mailpoet_paragraph { font-size: 12px; line-height: 16px; color: #afafaf; }\n#mailpoet_form_1 .mailpoet_form .mailpoet_paragraph { margin-bottom: 12px; }\n#mailpoet_form_1 .mailpoet_segment_label, #mailpoet_form_1 .mailpoet_text_label, #mailpoet_form_1 .mailpoet_textarea_label, #mailpoet_form_1 .mailpoet_select_label, #mailpoet_form_1 .mailpoet_radio_label, #mailpoet_form_1 .mailpoet_checkbox_label, #mailpoet_form_1 .mailpoet_list_label, #mailpoet_form_1 .mailpoet_date_label { display: block; font-weight: normal; }\n#mailpoet_form_1 .mailpoet_text, #mailpoet_form_1 .mailpoet_textarea, #mailpoet_form_1 .mailpoet_select, #mailpoet_form_1 .mailpoet_date_month, #mailpoet_form_1 .mailpoet_date_day, #mailpoet_form_1 .mailpoet_date_year, #mailpoet_form_1 .mailpoet_date { display: block; }\n#mailpoet_form_1 .mailpoet_text, #mailpoet_form_1 .mailpoet_textarea { width: 200px; }\n#mailpoet_form_1 .mailpoet_checkbox { vertical-align: middle; }\n#mailpoet_form_1 .mailpoet_submit { background-color: white !important; color: black !important; }\n#mailpoet_form_1 .mailpoet_divider {  }\n#mailpoet_form_1 .mailpoet_message {  }\n#mailpoet_form_1 .mailpoet_form_loading { width: 30px; text-align: center; line-height: normal; }\n#mailpoet_form_1 .mailpoet_form_loading > span { width: 5px; height: 5px; background-color: #5b5b5b; }\n#mailpoet_form_1 .mailpoet_form_html a, #mailpoet_form_1 .mailpoet_form_iframe a { background-color: transparent; color: #ff6262; cursor: pointer; -webkit-text-decoration-skip-ink: all; text-decoration-skip-ink: all; text-decoration-thickness: 1px; text-underline-offset: 3px; }\n#mailpoet_form_1 #mailpoet_form_1 .mailpoet_checkbox { width: 16px; height: 16px; position: relative; top: 4px; }#mailpoet_form_1{border: 1px solid #54595f;border-radius: 16px;background: #1a1a1c;color: #ffffff;text-align: left;}#mailpoet_form_1 form.mailpoet_form {padding: 24px;}#mailpoet_form_1{width: 100%;}#mailpoet_form_1 .mailpoet_message {margin: 0; padding: 0 20px;}\n        #mailpoet_form_1 .mailpoet_validate_success {color: #00d084}\n        #mailpoet_form_1 input.parsley-success {color: #00d084}\n        #mailpoet_form_1 select.parsley-success {color: #00d084}\n        #mailpoet_form_1 textarea.parsley-success {color: #00d084}\n      \n        #mailpoet_form_1 .mailpoet_validate_error {color: #ff6900}\n        #mailpoet_form_1 input.parsley-error {color: #ff6900}\n        #mailpoet_form_1 select.parsley-error {color: #ff6900}\n        #mailpoet_form_1 textarea.textarea.parsley-error {color: #ff6900}\n        #mailpoet_form_1 .parsley-errors-list {color: #ff6900}\n        #mailpoet_form_1 .parsley-required {color: #ff6900}\n        #mailpoet_form_1 .parsley-custom-error-message {color: #ff6900}\n      #mailpoet_form_1 .mailpoet_paragraph.last {margin-bottom: 0} @media (max-width: 500px) {#mailpoet_form_1 {background: #1a1a1c;}} @media (min-width: 500px) {#mailpoet_form_1 .last .mailpoet_paragraph:last-child {margin-bottom: 0}}  @media (max-width: 500px) {#mailpoet_form_1 .mailpoet_form_column:last-child .mailpoet_paragraph:last-child {margin-bottom: 0}} \n    <\/style>\n\n    <form\n      target=\"_self\"\n      method=\"post\"\n      action=\"https:\/\/designcompass.org\/wp-admin\/admin-post.php?action=mailpoet_subscription_form\"\n      class=\"mailpoet_form mailpoet_form_form mailpoet_form_html\"\n      novalidate\n      data-delay=\"\"\n      data-exit-intent-enabled=\"\"\n      data-trigger-mode=\"\"\n      data-click-trigger-selector=\"\"\n      data-font-family=\"\"\n      data-cookie-expiration-time=\"\"\n    >\n      <input type=\"hidden\" name=\"data[form_id]\" value=\"1\" \/>\n      <input type=\"hidden\" name=\"token\" value=\"1596f10373\" \/>\n      <input type=\"hidden\" name=\"api_version\" value=\"v1\" \/>\n      <input type=\"hidden\" name=\"endpoint\" value=\"subscribers\" \/>\n      <input type=\"hidden\" name=\"mailpoet_method\" value=\"subscribe\" \/>\n\n      <label class=\"mailpoet_hp_email_label\" style=\"display: none !important;\">Please leave this field empty<input type=\"email\" name=\"data[email]\"\/><\/label><h2 class=\"mailpoet-heading  mailpoet-has-font-size\" style=\"text-align: left; color: #ffffff; font-size: 24px; line-height: 1.4\"><span style=\"font-family:\" data-font=\"\" class=\"mailpoet-has-font\"><strong>\ub514\uc790\uc778 \ub098\uce68\ubc18 \ub274\uc2a4\ub808\ud130<\/strong><\/span><\/h2>\n<div class=\"mailpoet_paragraph \"><style>input[name=\"data[form_field_MjZhN2MxMDVmNmI2X2VtYWls]\"]::placeholder{color:#ffffff;opacity: 1;}<\/style><input type=\"email\" autocomplete=\"email\" class=\"mailpoet_text\" id=\"form_email_1\" name=\"data[form_field_MjZhN2MxMDVmNmI2X2VtYWls]\" title=\"\uc774\uba54\uc77c \uc8fc\uc18c\" value=\"\" style=\"width:100%;box-sizing:border-box;background-color:#212123;border-style:solid;border-radius:8px !important;border-width:1px;border-color:#3d3d41;padding:12px;margin: 0 auto 0 0;font-size:13px;line-height:1.5;height:auto;color:#ffffff;\" data-automation-id=\"form_email\"  placeholder=\"\uc774\uba54\uc77c \uc8fc\uc18c *\" aria-label=\"\uc774\uba54\uc77c \uc8fc\uc18c *\" data-parsley-errors-container=\".mailpoet_error_9fjmz\" data-parsley-required=\"true\" required aria-required=\"true\" data-parsley-minlength=\"6\" data-parsley-maxlength=\"150\" data-parsley-type-message=\"This value should be a valid email.\" data-parsley-required-message=\"This field is required.\"\/><span class=\"mailpoet_error_9fjmz\"><\/span><\/div>\n<div class=\"mailpoet_paragraph \"><fieldset><input type=\"hidden\" value=\"1\"  name=\"data[cf_1]\" \/><label class=\"mailpoet_checkbox_label\" for=\"mailpoet_checkbox_1\" style=\"font-size: 13px;line-height: 1.2;\"><input type=\"checkbox\" class=\"mailpoet_checkbox\" id=\"mailpoet_checkbox_1\" name=\"data[cf_1]\" value=\"1\" data-parsley-errors-container=\".mailpoet_error_1ql0b\" data-parsley-required=\"true\" required aria-required=\"true\" data-parsley-required-message=\"This field is required.\" data-parsley-group=\"custom_field_1\" \/> (\ud544\uc218)\uc774\uc6a9\uc57d\uad00, \uac1c\uc778\uc815\ubcf4\ucc98\ub9ac\ubc29\uce68\uc5d0 \ub3d9\uc758\ud569\ub2c8\ub2e4.<\/label><\/fieldset><span class=\"mailpoet_error_1ql0b\"><\/span><\/div>\n<div class=\"mailpoet_paragraph \"><fieldset><input type=\"hidden\" value=\"1\"  name=\"data[cf_2]\" \/><label class=\"mailpoet_checkbox_label\" for=\"mailpoet_checkbox_2\" style=\"font-size: 13px;line-height: 1.2;\"><input type=\"checkbox\" class=\"mailpoet_checkbox\" id=\"mailpoet_checkbox_2\" name=\"data[cf_2]\" value=\"1\" data-parsley-errors-container=\".mailpoet_error_fp8f1\" data-parsley-required=\"true\" required aria-required=\"true\" data-parsley-required-message=\"This field is required.\" data-parsley-group=\"custom_field_2\" \/> (\ud544\uc218)\uad11\uace0\uc131 \uc815\ubcf4 \uc218\uc2e0\uc5d0 \ub3d9\uc758\ud569\ub2c8\ub2e4<\/label><\/fieldset><span class=\"mailpoet_error_fp8f1\"><\/span><\/div>\n<div class=\"mailpoet_paragraph \" style=\"font-size: 13px;line-height: 1.2;\"><a style=\"font-size:12px;color: #afafaf;text-decoration:underline\" href=\"https:\/\/designcompass.org\/terms-of-service\">\uc774\uc6a9\uc57d\uad00<\/a>  <a style=\"font-size:12px;color: #afafaf;text-decoration:underline\" href=\"https:\/\/designcompass.org\/privacy-policy\">\uac1c\uc778\uc815\ubcf4\ucc98\ub9ac\ubc29\uce68<\/a>   <a style=\"font-size:12px;color: #afafaf;text-decoration:underline\" href=\"https:\/\/designcompass.org\/marketing-agreement\">\ub9c8\ucf00\ud305\uc218\uc2e0\ub3d9\uc758<\/a><\/div>\n<div class=\"mailpoet_paragraph \"><input type=\"submit\" class=\"mailpoet_submit\" value=\"\ub274\uc2a4\ub808\ud130 \uad6c\ub3c5\" data-automation-id=\"subscribe-submit-button\" style=\"width:100%;box-sizing:border-box;background-color:#000000;border-style:solid;border-radius:40px !important;border-width:0px;border-color:#313131;padding:16px;margin: 0 auto 0 0;font-size:NaN;line-height:1.5;height:auto;color:#ffffff;font-weight:bold;\" \/><span class=\"mailpoet_form_loading\"><span class=\"mailpoet_bounce1\"><\/span><span class=\"mailpoet_bounce2\"><\/span><span class=\"mailpoet_bounce3\"><\/span><\/span><\/div>\n\n      <div class=\"mailpoet_message\">\n        <p class=\"mailpoet_validate_success\"\n                style=\"display:none;\"\n                >\uc815\uc0c1\uc801\uc778 \uc8fc\uc18c\uc778\uc9c0 \ud655\uc778\ud558\ub294 \uc774\uba54\uc77c\uc744 \ubcf4\ub0c8\uc2b5\ub2c8\ub2e4. \ubc1b\uc740 \uc774\uba54\uc77c\uc5d0\uc11c &#039;\ud65c\uc131\ud654&#039; \ubc84\ud2bc\uc744 \ub20c\ub7ec\uc8fc\uc138\uc694.\n        <\/p>\n        <p class=\"mailpoet_validate_error\"\n                style=\"display:none;\"\n                >        <\/p>\n      <\/div>\n    <\/form>\n\n      <\/div>\n\n  \n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4130900524608986\" crossorigin=\"anonymous\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block\" data-ad-format=\"autorelaxed\" data-ad-client=\"ca-pub-4130900524608986\" data-ad-slot=\"2908097030\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">\ube44\uc2b7\ud55c \uae00<\/h2>\n\n\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">\ucd5c\uadfc \uae00<\/h2>\n\n\n","protected":false},"excerpt":{"rendered":"<p>\uc2a4\ud0c0\ud544\ub4dc\uac00 \ucd9c\uc2dc\ud569\ub2c8\ub2e4. \uc2a4\ud0c0\ud544\ub4dc\ub294 \uc5d8\ub354\uc2a4\ud06c\ub864, \ud3f4\uc544\uc6c3\uc744 \ub9cc\ub4e0 \ubca0\ub370\uc2a4\ub2e4\uac00 25\ub144\ub9cc\uc5d0 \uc0c8\ub86d\uac8c \ucd9c\uc2dc\ud558\ub294 IP\uc785\ub2c8\ub2e4. \ucd5c\ucd08 \uc544\uc774\ub514\uc5b4\ub294 \ud1a0\ub4dc \ud558\uc6cc\ub4dc\uac00 10\ub300 \ub54c \uc560\ud50c 2 \ucef4\ud4e8\ud130\ub85c \ub9cc\ub4e0 \uac8c\uc784\uc5d0\uc11c \uc2dc\uc791\ub410\ub2e4\uace0 \ud569\ub2c8\ub2e4. \uc2e4\uc81c \uac1c\ubc1c \ucc29\uc218\ub294 2017\ub144\ubd80\ud130 \uc2dc\uc791\ub410\uc73c\uba70 \uc5d1\uc2a4\ubc15\uc2a4 \ub3c5\uc810\uc73c\ub85c \uc5bc\ub9ac \uc5b5\uc138\uc2a4\ub294 9\uc6d4 1\uc77c\uc5d0 \uc5f4\ub9ac\uba70 9\uc6d4 6\uc77c\uc5d0 \uc815\uc2dd \ucd9c\uc2dc\ud569\ub2c8\ub2e4. \ud83d\udc41\ufe0f&nbsp;\ub514\uc790\uc774\ub108\uc758 \ub208 \ub290\uc2a8\ud55c \uc6b0\uc8fc \uc5ec\ud589\ubcf4\ub2e4\ub294 \ubc00\ub3c4 \ub192\uc740 \ud589\uc131 \ub4dc\ub77c\ub9c8\uac00 \ub420 \uac83\uc73c\ub85c \ubcf4\uc785\ub2c8\ub2e4. 4\uac1c\uc758 \ubcc4\uc744 \ud0d0\ud5d8\ud558\uba70 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17874,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4,621],"tags":[69,185,370,377,467,596,597,717,758,763],"class_list":["post-17873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-service","tag-69","tag-185","tag-ui","tag-ux","tag-ui-ux","tag-interaction","tag-597","tag-717","tag-758","tag-763"],"acf":[],"jetpack_featured_media_url":"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/08\/star-field-01.png","publishpress_future_action":{"enabled":false,"date":"2026-05-21 06:05:53","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/posts\/17873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/comments?post=17873"}],"version-history":[{"count":0,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/posts\/17873\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/media\/17874"}],"wp:attachment":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/media?parent=17873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/categories?post=17873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/tags?post=17873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}