{"id":14934,"date":"2023-06-07T10:09:35","date_gmt":"2023-06-07T01:09:35","guid":{"rendered":"https:\/\/designcompass.org\/?p=14934"},"modified":"2023-06-07T10:15:02","modified_gmt":"2023-06-07T01:15:02","slug":"apple-design-award-2023","status":"publish","type":"post","link":"https:\/\/designcompass.org\/en\/2023\/06\/07\/apple-design-award-2023\/","title":{"rendered":"Apple Design Awards 2023: Emphasis on &#039;all together&#039;"},"content":{"rendered":"<p>The Apple Design Awards 2023 winners and finalists have been revealed. The Apple Design Awards are based on innovation, originality, and technical achievement. Apple selected the award-winning works under the themes of Inclusivity, Delight and Fun, Interaction, Social Impact, Visuals and Graphics, and Innovation. We&#039;ve rounded up some of the most impressive offerings from our many amazing awards and nominations.<\/p>\n\n\n\n<p>*There are many great services that we have not introduced, so be sure to check out the rest of the services in the source link.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-06-1024x1024.png\" alt=\"\" class=\"wp-image-14936\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-06-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-06-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-06-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-06-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-06-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-06-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-06-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-06-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-06-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-06-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-06-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-06.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u00a9Apple<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-07-1024x1024.png\" alt=\"\" class=\"wp-image-14941\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-07-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-07-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-07-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-07-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-07-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-07-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-07-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-07-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-07-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-07-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-07-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-07.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u00a9Apple<\/figcaption><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83d\udc41\ufe0f Designer Eye<\/h3>\n\n\n\n<p><strong>universe Universe<\/strong> There are many blocky website builders, but the universe is different. &#039;Our goal is to make this technology accessible to everyone.&#039; Make decisions that fit your vision. Accessibility upgrades have helped more people use the app. For people with visual impairments, we designed the experience to create websites with VoiceOver. It is a wonderful service that imagines a world where anyone can create a website in natural language by studying AI in the future.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-02-1024x1024.png\" alt=\"\" class=\"wp-image-14937\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-02-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-02-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-02-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-02-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-02-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-02-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-02-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-02-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-02-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-02-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-02-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-02.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u00a9Apple<\/figcaption><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>stitch stitch<\/strong> This app is full of fun to use. Mobile applications come to mind with various creative challenges in the past. The tactile surface is harmonious with the cute artwork (even the icons are cute!). We have created a puzzle of the right difficulty so that it is not too difficult to make you give up, and not too easy to make meaningless touches. The joy of completion makes me feel like I made the work rather than clearing the stage.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-03-1024x1024.png\" alt=\"\" class=\"wp-image-14938\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-03-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-03-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-03-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-03-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-03-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-03-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-03-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-03-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-03-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-03-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-03-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-03.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u00a9Apple<\/figcaption><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Flighty<\/strong> When it comes to usability, being able to check information anytime, anywhere is important. The higher the price of missing information, the more important it is. The best example is airline tickets. You have to be prepared when something goes wrong. Flyty uses the widget to quickly check the necessary information before boarding the plane. You can easily and comfortably share important information with your companions or acquaintances. It is also impressive to apply the airport&#039;s signage grammar to the app.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-04-1024x1024.png\" alt=\"\" class=\"wp-image-14939\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-04-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-04-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-04-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-04-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-04-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-04-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-04-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-04-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-04-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-04-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-04-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-04.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u00a9Apple<\/figcaption><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Swing Vision SwingVision<\/strong> Using the Apple Watch, the speed of the swing is measured and the score is measured. It is a great example of using technology such as cameras and machine learning. It also verifies line in\/line out. You can practice your serve alone by setting up a target area on the court, or you can record the game and share highlights. It&#039;s a great experience that made the experience available only in games available offline.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-05-1024x1024.png\" alt=\"\" class=\"wp-image-14940\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-05-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-05-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-05-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-05-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-05-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-05-12x12.png 12w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-05-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-05-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-05-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-05-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-05-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-05.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u00a9Apple<\/figcaption><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83d\udcd5 Editor&#039;s Notes<\/h3>\n\n\n\n<p>There are so many interesting services that it&#039;s difficult to think about which service to record. It&#039;s cool that Apple selects valuable applications and introduces them to the world. It is also impressive that Inclusivity, which embodies the value of diversity and inclusion, was placed first in the award category. I am grateful that the world&#039;s No. 1 company shines light on the value of inclusion, which is difficult to measure.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">More and Sources<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/developer.apple.com\/design\/awards\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/developer.apple.com\/design\/awards\/<\/a><\/li>\n<\/ul>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4130900524608986\" crossorigin=\"anonymous\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block\" data-ad-format=\"autorelaxed\" data-ad-client=\"ca-pub-4130900524608986\" data-ad-slot=\"2908097030\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Similar posts<\/h2>\n\n\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">recent posts<\/h2>","protected":false},"excerpt":{"rendered":"<p>\uc560\ud50c \ub514\uc790\uc778 \uc5b4\uc6cc\ub4dc 2023 \uc218\uc0c1\uc790\uc640 \uacb0\uc120 \uc9c4\ucd9c\uc790\uac00 \uacf5\uac1c\ub410\uc2b5\ub2c8\ub2e4. \uc560\ud50c \ub514\uc790\uc778 \uc5b4\uc6cc\ub4dc\ub294 \ud601\uc2e0\uc131, \ub3c5\ucc3d\uc131, \uae30\uc220\uc801 \uc131\ucde8\ub97c \uae30\uc900\uc73c\ub85c \uacb0\uc815\ud569\ub2c8\ub2e4. \uc560\ud50c\uc740 Inclusivity, Delight and Fun, Interaction, Social Impact, Visuals and Graphics, Innovation\ub97c \uc8fc\uc81c\ub85c \uc218\uc0c1\uc791\uc744 \uc120\uc815\ud588\uc2b5\ub2c8\ub2e4. \uc5ec\ub7ec \uba4b\uc9c4 \uc218\uc0c1\uc791\uacfc \ud6c4\ubcf4 \uc911 \uc778\uc0c1 \uae4a\uc740 \uc11c\ube44\uc2a4\ub97c \ubaa8\uc558\uc2b5\ub2c8\ub2e4. *\uc18c\uac1c\ud558\uc9c0 \ubabb\ud55c \ud6cc\ub96d\ud55c \uc11c\ube44\uc2a4\ub3c4 \ub9ce\uc73c\ub2c8 \uaf2d \ucd9c\ucc98 \ub9c1\ud06c\uc5d0\uc11c \ub098\uba38\uc9c0 \uc11c\ube44\uc2a4\ub3c4 \ud655\uc778\ud574\ubcf4\uc138\uc694. \ud83d\udc41\ufe0f&nbsp;\ub514\uc790\uc774\ub108\uc758 \ub208 \uc720\ub2c8\ubc84\uc2a4 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14935,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4,621],"tags":[69,185,370,377,467,596,597,717,758,763],"class_list":["post-14934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-service","tag-69","tag-185","tag-ui","tag-ux","tag-ui-ux","tag-interaction","tag-597","tag-717","tag-758","tag-763"],"acf":[],"jetpack_featured_media_url":"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/06\/apple-design-award-08.png","publishpress_future_action":{"enabled":false,"date":"2026-05-21 08:08:43","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/posts\/14934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/comments?post=14934"}],"version-history":[{"count":0,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/posts\/14934\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/media\/14935"}],"wp:attachment":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/media?parent=14934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/categories?post=14934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/tags?post=14934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}