{"id":11415,"date":"2023-03-20T09:39:31","date_gmt":"2023-03-20T00:39:31","guid":{"rendered":"https:\/\/designcompass.org\/?p=11415"},"modified":"2023-03-20T09:48:14","modified_gmt":"2023-03-20T00:48:14","slug":"microsoft-copilot","status":"publish","type":"post","link":"https:\/\/designcompass.org\/en\/2023\/03\/20\/microsoft-copilot\/","title":{"rendered":"Microsoft Copilot: Clippy is smarter than you think"},"content":{"rendered":"<p>Microsoft unveiled AI Copilot at the &#039;Future of Work&#039; event. It applies to Word, Excel, Outlook, PowerPoint, and Teams, which are everyday tools provided by Microsoft. You can even use Power Apps to create apps by writing the desired functionality in the prompt. It will fundamentally change the way we work and increase productivity. <a href=\"https:\/\/designcompass.org\/en\/2023\/03\/16\/google-generative-ai\/\" target=\"_blank\" rel=\"noreferrer noopener\">Google also recently applied AI to work tools.<\/a>But it&#039;s like the invention of the steam engine. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-03-1024x1024.png\" alt=\"\" class=\"wp-image-11417\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-03-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-03-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-03-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-03-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-03-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-03-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-03-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-03-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-03-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-03-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-03.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>\u00a9Microsoft<\/figcaption><\/figure>\n\n\n\n<p>Specifically, Business Chat can use all of your apps and data to help you summarize chats, compose emails, find key events, and even create project plans. You can sign in with your work account or use it in Teams. Typing in \u201cTell the team how you updated the product strategy\u201d will automatically generate the current update status.<\/p>\n\n\n\n<p>It is full of great experiences as well as writing and summarizing the text you are accustomed to with ChatGPT. Just enter your ideas to create a finished presentation, and Excel visualizes the data you want and summarizes your insights.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-10-1024x1024.png\" alt=\"\" class=\"wp-image-11418\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-10-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-10-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-10-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-10-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-10-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-10-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-10-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-10-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-10-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-10-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-10.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>\u00a9Microsoft<\/figcaption><\/figure>\n\n\n\n<p>Microsoft has continued to challenge office assistants that help users&#039; productivity by creating Rocky and Cippy, which have given us annoyance. This Copilot seems really smart, so what changes will it make in the future?<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Introducing Microsoft 365 Copilot | Your Copilot for Work\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/S7xTBa93TX8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><figcaption>\u00a9Microsoft<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Next generation AI in Power Apps is changing how you develop low-code applications\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/TOsRhrSXohY?start=1&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><figcaption>\u00a9Microsoft<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-04-1024x1024.png\" alt=\"\" class=\"wp-image-11419\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-04-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-04-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-04-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-04-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-04-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-04-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-04-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-04-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-04-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-04-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-04.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>\u00a9Microsoft<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-05-1024x1024.png\" alt=\"\" class=\"wp-image-11420\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-05-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-05-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-05-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-05-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-05-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-05-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-05-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-05-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-05-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-05-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-05.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>\u00a9Microsoft<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-06-1024x1024.png\" alt=\"\" class=\"wp-image-11421\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-06-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-06-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-06-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-06-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-06-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-06-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-06-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-06-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-06-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-06-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-06.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>\u00a9Microsoft<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-07-1024x1024.png\" alt=\"\" class=\"wp-image-11422\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-07-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-07-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-07-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-07-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-07-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-07-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-07-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-07-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-07-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-07-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-07.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>\u00a9Microsoft<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-08-1024x1024.png\" alt=\"\" class=\"wp-image-11423\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-08-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-08-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-08-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-08-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-08-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-08-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-08-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-08-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-08-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-08-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-08.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>\u00a9Microsoft<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-09-1024x1024.png\" alt=\"\" class=\"wp-image-11424\" srcset=\"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-09-1024x1024.png 1024w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-09-300x300.png 300w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-09-100x100.png 100w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-09-600x600.png 600w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-09-150x150.png 150w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-09-768x768.png 768w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-09-1536x1536.png 1536w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-09-924x924.png 924w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-09-671x671.png 671w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-09-1320x1320.png 1320w, https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-09.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>\u00a9Microsoft<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">More and Sources<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/news.microsoft.com\/ko-kr\/2023\/03\/17\/introducing-microsoft-365-copilot\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/news.microsoft.com\/ko-kr\/2023\/03\/17\/introducing-microsoft-365-copilot\/<\/a><\/li><\/ul>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4130900524608986\" crossorigin=\"anonymous\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block\" data-ad-format=\"autorelaxed\" data-ad-client=\"ca-pub-4130900524608986\" data-ad-slot=\"2908097030\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Similar posts<\/h2>\n\n\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">recent posts<\/h2>","protected":false},"excerpt":{"rendered":"<p>\ub9c8\uc774\ud06c\ub85c\uc18c\ud504\ud2b8\uac00 \u2018Future of Work\u2019 \uc774\ubca4\ud2b8\uc5d0\uc11c AI Copilot\uc744 \uacf5\uac1c\ud588\uc2b5\ub2c8\ub2e4. \ub9c8\uc774\ud06c\ub85c\uc18c\ud504\ud2b8\uc5d0\uc11c \uc81c\uacf5\ud558\ub294 \uc77c\uc0c1 \ub3c4\uad6c\uc778 \uc6cc\ub4dc, \uc5d1\uc140, \uc544\uc6c3\ub8e9, \ud30c\uc6cc\ud3ec\uc778\ud2b8, \ud300\uc988\uc5d0 \uc801\uc6a9\ub429\ub2c8\ub2e4. \uc2ec\uc9c0\uc5b4 Power Apps\ub97c \uc774\uc6a9\ud574 \ud504\ub86c\ud504\ud2b8\uc5d0 \uc6d0\ud558\ub294 \uae30\ub2a5\uc744 \uc791\uc131\ud558\uba74 \uc571\uc744 \ub9cc\ub4e4 \uc218 \uc788\uc2b5\ub2c8\ub2e4. \uc77c\ud558\ub294 \ubc29\uc2dd\uc744 \uadfc\ubcf8\uc801\uc73c\ub85c \ubc14\uafb8\uace0 \uc0dd\uc0b0\uc131\uc774 \uc99d\ub300\ub420 \uac83\uc774\ub77c \ubc1d\ud614\uc2b5\ub2c8\ub2e4. \uad6c\uae00\ub3c4 \ucd5c\uadfc \uc5c5\ubb34\uc6a9 \ub3c4\uad6c\uc5d0 AI\ub97c \uc801\uc6a9\ud588\ub294\ub370 \ub9c8\uce58 \uc99d\uae30\uae30\uad00\uc758 \ubc1c\uba85\uac19\ub124\uc694. \ud2b9\ud788 \ube44\uc988\ub2c8\uc2a4 \ucc57\uc740 \uc0ac\uc6a9\uc790\uc758 \ubaa8\ub4e0 \uc571\uacfc \ub370\uc774\ud130\ub97c \uc774\uc6a9\ud574 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11427,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4,621],"tags":[69,100,185,370,377,467,596,597,613,717,758,763,791],"class_list":["post-11415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-service","tag-69","tag-100","tag-185","tag-ui","tag-ux","tag-ui-ux","tag-interaction","tag-597","tag-ai","tag-717","tag-758","tag-763","tag-openai"],"acf":[],"jetpack_featured_media_url":"https:\/\/designcompass.org\/wp-content\/uploads\/2023\/03\/copilot-02.png","publishpress_future_action":{"enabled":false,"date":"2026-05-21 06:00:44","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/posts\/11415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/comments?post=11415"}],"version-history":[{"count":0,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/posts\/11415\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/media\/11427"}],"wp:attachment":[{"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/media?parent=11415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/categories?post=11415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/designcompass.org\/en\/wp-json\/wp\/v2\/tags?post=11415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}